{"id":33434,"date":"2016-02-05T16:55:01","date_gmt":"2016-02-05T15:55:01","guid":{"rendered":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?p=33434"},"modified":"2024-10-29T18:49:17","modified_gmt":"2024-10-29T17:49:17","slug":"diners-croisieres-nouvel-an-paris","status":"publish","type":"post","link":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/","title":{"rendered":"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s"},"content":{"rendered":"<p>Imaginez-vous glissant sur la Seine, avec la Tour Eiffel et Notre-Dame illumin\u00e9es en toile de fond, tout en d\u00e9gustant un d\u00eener gastronomique.<\/p>\n<p>C&rsquo;est l&rsquo;exp\u00e9rience inoubliable que promettent les d\u00eeners-croisi\u00e8res de la Saint-Sylvestre.<\/p>\n<p>Mais lequel choisir parmi tant d&rsquo;offres s\u00e9duisantes ?<\/p>\n<p>J&rsquo;ai d\u00e9cortiqu\u00e9 pour vous les meilleures options pour garantir une soir\u00e9e m\u00e9morable. Et je n&rsquo;ai laiss\u00e9 pass\u00e9 aucun d\u00e9tail !<\/p>\n<p>\u26a0\ufe0f <b>Conseil important<\/b> : ces croisi\u00e8res sont pris\u00e9es, alors anticipez et r\u00e9servez au moins un mois \u00e0 l&rsquo;avance.<\/p>\n<p>&nbsp;<\/p>\n<h3>Mes recommandations en bref<\/h3>\n<p>Pour tous ceux et celles qui n\u2019ont pas de temps \u00e0 perdre, voici mes d\u00eeners-croisi\u00e8res favoris :<\/p>\n<ul>\n<li aria-level=\"1\"><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/nouvel-an-marina-de-paris-1004?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Paris Seine<\/a> : un d\u00eener gastronomique et une croisi\u00e8re chic \u00e0 un prix raisonnable. Menu v\u00e9g\u00e9tarien inclus.<\/li>\n<li aria-level=\"1\"><a href=\"https:\/\/www.cometoparis.com\/fre\/nouvel-an-a-paris\/bateau-le-theo-m9000897?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Le Th\u00e9o<\/a> : Propose deux options de travers\u00e9es aux prix les plus bas sans rien sacrifier de la qualit\u00e9 du diner et de la croisi\u00e8re. Que demander de plus ?<\/li>\n<li aria-level=\"1\"><a href=\"https:\/\/www.vedettesdupontneuf.com\/diner-croisiere-parisien-reveillon\/\" target=\"_blank\" rel=\"nofollow noopener\">Vedettes du Pont-Neuf<\/a> : une animation musicale atypique, qui vous introduira \u00e0 tous le r\u00e9pertoire de la chanson populaire fran\u00e7aise, sans vous ruiner.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a578b60e29e0\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #555555;color:#555555\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #555555;color:#555555\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a578b60e29e0\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#1-Bateaux-Mouches\" >1) Bateaux Mouches<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#2-Le-Diamant-Bleu\" >2) Le Diamant Bleu<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#3-LExcellence\" >3) L&rsquo;Excellence<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#4-Les-Bateaux-Parisiens\" >4) Les Bateaux Parisiens<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#5-Le-Mirage\" >5) Le Mirage<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#6-Paris-Seine\" >6) Paris Seine<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#7-Le-Theo\" >7) Le Th\u00e9o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#8-Vedettes-du-Pont-Neuf\" >8) Vedettes du Pont Neuf<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#Tableau-comparatif-des-diners-croisieres-du-Nouvel-An-a-Paris\" >Tableau comparatif des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"1-Bateaux-Mouches\"><\/span>1) Bateaux Mouches<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_33435\" aria-describedby=\"caption-attachment-33435\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33435\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg\" alt=\"Bateaux Mouches\" width=\"620\" height=\"347\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville-475x266.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-33435\" class=\"wp-caption-text\">Saint-Sylvestre r\u00e9veillon, bateaux mouches<\/figcaption><\/figure>\n<p>Pour la Saint-Sylvestre, la compagnie des Bateaux-Mouches vous invite \u00e0 une soir\u00e9e gourmande et festive (en famille ou entre amis) rythm\u00e9e par un duo de musiciens et la voix m\u00e9lodieuse d\u2019une chanteuse.<\/p>\n<p>Vous pourrez profiter d\u2019un <b>repas gastronomique complet<\/b>, en commen\u00e7ant par quelques bouch\u00e9es de <b>caviar de Neuvic, <\/b>suivi d\u2019un d\u00f4me de <b>foie gras,\u00a0<\/b>accompagn\u00e9 d&rsquo;une compot\u00e9e de cerises noires sur biscuit moelleux au pain d\u2019\u00e9pices.<\/p>\n<p>La pi\u00e8ce de r\u00e9sistance consistera en un <strong>filet de b\u0153uf Angus<\/strong>, accompagn\u00e9 d&rsquo;un <strong>risotto de panais au parmesan<\/strong>, de <strong>l\u00e9gumes<\/strong> <strong>croquants<\/strong>, ainsi que d&rsquo;une <strong>sauce aux morilles<\/strong>.<\/p>\n<p>Et les derni\u00e8res \u00e9tapes de cette balade culinaire vous conduiront jusqu\u2019\u00e0 un Brie Savarin AOP \u00e0 la truffe, et \u00e0 une <strong>sph\u00e8re chocolat noir<\/strong>, <strong>douceur d\u2019agrumes<\/strong>.<\/p>\n<p>Une <b>coupe de champagne<\/b> Jacquart Blanc de Blanc vous sera servie durant l\u2019ap\u00e9ritif. Et vous pourrez siroter au cours du repas une <b>1\/2 bouteille de vin rouge<\/b> Crozes Hermitages &#8211; La Rolande ou en rester au mousseux\u00a0 avec une 1\/2 bouteille de Jacquard. Selon vos pr\u00e9f\u00e9rences, vous pourrez terminer par un caf\u00e9, un th\u00e9 ou un cognac \u201cAndr\u00e9 Petit\u201d.<\/p>\n<p>Si les boissons alcoolis\u00e9es n\u2019ont pas votre faveur, une 1\/2 bouteille d&rsquo;Evian ou de Badoit (pour 2) sera disponible, \u00e0 moins que vous ne pr\u00e9f\u00e9riez piocher parmi les sodas et jus de fruits (33 cl) mis \u00e0 votre disposition.<\/p>\n<p><b>\ud83d\udd57 Horaires :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">\u00a020h30 : Embarquement Pont de l\u2019Alma, Paris 8e.<\/li>\n<li aria-level=\"1\">\u00a021h00 : D\u00e9part en croisi\u00e8re<\/li>\n<li aria-level=\"1\">\u00a023h30 : Retour \u00e0 quai et soir\u00e9e dansante sur les quais jusqu\u2019\u00e0 02h00<\/li>\n<li aria-level=\"1\">\u00a002h00 : D\u00e9barquement<\/li>\n<\/ul>\n<p><b>\ud83d\udcb0 Prix <\/b>: \u20ac460\/personne de 20h30 \u00e0 02h00.<\/p>\n<p><b>\ud83d\ude0d On aime :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Le parking gratuit<\/li>\n<li aria-level=\"1\">L\u2019animation musicale<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/nouvel-an-bateaux-mouches-1002?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Informations et r\u00e9servations<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"2-Le-Diamant-Bleu\"><\/span>2) Le Diamant Bleu<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_33453\" aria-describedby=\"caption-attachment-33453\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33453\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/croisiere-diamant-bl.jpg\" alt=\"Diamant bleu\" width=\"620\" height=\"930\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/croisiere-diamant-bl.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/croisiere-diamant-bl-317x475.jpg 317w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-33453\" class=\"wp-caption-text\">Le Diamant Bleu<\/figcaption><\/figure>\n<p>Embarquez sur un v\u00e9ritable palais flottant pour r\u00e9veillonner en grande pompe \u00e0 bord d\u2018un des fleurons de la flotte parisienne !<\/p>\n<p>Le Diamant Bleu est une p\u00e9niche moderne au design \u00e9l\u00e9gant, qui offre un <b>cadre de luxe <\/b>\u00e0 tous ceux qui souhaitent f\u00eater la nouvelle ann\u00e9e dans une ambiance festive. Spacieux (70 m de long et 10 m de large), il peut accueillir jusqu&rsquo;\u00e0 450 convives dans son salon climatis\u00e9 et dispose d\u2019un <b>pont-terrasse<\/b> en teck depuis lequel vous pourrez admirer la Seine.<\/p>\n<p>L\u2019un de ses atouts principaux est sans doute la <b>vue panoramique<\/b> qu&rsquo;offrent ses <b>34 baies vitr\u00e9es<\/b>.<\/p>\n<p>En tant que passagers de cette petite croisi\u00e8re vous pourrez aussi profiter d\u2019une soir\u00e9e anim\u00e9e par un DJ exp\u00e9riment\u00e9.<\/p>\n<p>Deux types de travers\u00e9es sont disponibles :<\/p>\n<p><b>1\ufe0f\u20e3 Une balade nautique de 18h15 \u00e0 20h15<\/b>, agr\u00e9ment\u00e9e d\u2019une <b>animation musicale<\/b> et d\u2019un <b>repas gastronomique<\/b>. Ce dernier s\u2019ouvrira par un cocktail du capitaine (avec ou sans alcool), et un <strong>foie gras poivr\u00e9 cuit au torchon et son chutney de kumquat<\/strong>.<\/p>\n<p>Ensuite, un<b> f<strong>ilet mignon de veau,<\/strong><\/b> agr\u00e9ment\u00e9 d&rsquo;un <strong>millefeuille<\/strong><b><strong> d\u2019Agatha truff\u00e9<\/strong><\/b>\u00a0fera office de plat principal, avant qu\u2019un dessert myst\u00e8re (servi avec une coupe de champagne) ne vienne conclure ce moment gourmand.<\/p>\n<p>Vous disposerez d\u2019une 1\/2 bouteille de vin par personne et\u00a0 d\u2019une 1\/2 bouteille d&rsquo;eau pour 2.<\/p>\n<p><b>Prix<\/b>: 199 \u20ac<\/p>\n<p><b>2\ufe0f\u20e3 Un p\u00e9riple de 3 heures sur la Seine \u00e0 partir de 21h15<\/b> qui donnera lieu \u00e0 une soir\u00e9e dansante aux bords des quais de 00h30 \u00e0 2h00.<\/p>\n<p>En optant pour cette travers\u00e9e, vous b\u00e9n\u00e9ficierez du m\u00eame menu gastronomique, enrichi cependant de <b>trois pi\u00e8ces ap\u00e9ritives<\/b> pour accompagner le cocktail du capitaine et d\u2019une <b>d\u00e9licieuse entr\u00e9e n<strong>oix de Saint-Jacques snack\u00e9es et d&rsquo;un homard juste-cuit<\/strong><\/b>, en plus du foie gras.<\/p>\n<p><b>\ud83d\udcb0 Prix: <\/b>450 \u20ac<\/p>\n<p><b>\ud83d\ude0d On aime :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">La soir\u00e9e dansante avec DJ.<\/li>\n<li aria-level=\"1\">Repas gastronomique pr\u00e9par\u00e9 par un chef \u00e9toil\u00e9.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/reveillon-croisiere-sur-la-seine-9000520?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Informations et r\u00e9servations<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"3-LExcellence\"><\/span>3) L&rsquo;Excellence<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/B7VsnVTo_KK\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/B7VsnVTo_KK\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"nofollow noopener\">Une publication partag\u00e9e par YACHTS DE PARIS (@yachtsdeparis)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Cet \u00e9l\u00e9gant navire de la compagnie des Yachts de Paris offre une croisi\u00e8re conviviale et chaleureuse dans une embarcation \u00e0<b> taille humaine<\/b> (60 personnes maximum).<\/p>\n<p>Les convives rassembl\u00e9s pour f\u00eater la Saint-Sylvestre pourront se r\u00e9galer d\u2019un menu somptueux, dans un splendide bateau <b>par\u00e9 de cuivre<\/b> et de luxueuses <b>boiseries d&rsquo;acajou<\/b>.<\/p>\n<p>Le repas commencera sur une note explosive avec un \u00e9ventail mirobolant <b>d\u2019amuse-bouche<\/b> :<\/p>\n<ul>\n<li aria-level=\"1\">Comme un \u00ab\u00a0nougat\u00a0\u00bb d&rsquo;Ossau Iraty relev\u00e9 d&rsquo;un condiment \u00e0 l&rsquo;orange<\/li>\n<li aria-level=\"1\">Ravigote de c\u00e8pes, parmenti\u00e8re, vermicelles de riz frits et croustille<\/li>\n<li aria-level=\"1\">Sabl\u00e9 fleuri aux l\u00e9gumes, \u00e0 l\u2019huile d\u2019olive et au piment d&rsquo;Espelette<\/li>\n<li aria-level=\"1\">Croustille de pomme de terre parmesan au tarama et citron vert<\/li>\n<li aria-level=\"1\">Gambas marin\u00e9es \u00e0 la cardamone &amp; patate douce miell\u00e9e<\/li>\n<li aria-level=\"1\">Tartelette craquante d&rsquo;une blanquette de veau, riz pilaf<\/li>\n<\/ul>\n<p>Il y en a r\u00e9ellement pour tous les go\u00fbts.<\/p>\n<p>Vos papilles seront certainement d\u00e9j\u00e0 conquises par ce festival de saveurs, mais le spectacle continue.<\/p>\n<p>En entr\u00e9e vous pourrez d\u00e9guster une<b> la Saint-Jacques marin\u00e9es fa\u00e7on gravlax<\/b> r\u00e9moulade et cresson, laquelle sera suivie par un <strong>Veau en Mignon<\/strong>, <strong>c\u00e8pes au jus<\/strong> et \u00e9mulsion \u00e0 la <strong>truffe blanche d&rsquo;Alba<\/strong>.<b><\/b><\/p>\n<p><strong>La Cabosse<\/strong>, une <strong>infusion de f\u00e8ves de cacao<\/strong> annoncera la fin des r\u00e9jouissances, qui seront d\u00e9finitivement achev\u00e9es lorsque vous aurez fait un sort aux mignardises pr\u00e9vues par le chef (Macaron vanille Bourbon de Madagascar &amp; Cube bonbon de chocolat Len\u00f4tre).<\/p>\n<p>Pour vous d\u00e9salt\u00e9rer, 2 coupes de champagne (par personne) Jacquard Signature vous seront servies, ainsi qu\u2019une bouteille de vin \u00e0 partager \u00e0 deux (un blanc, Pouilly Fum\u00e9 les Clairi\u00e8res \u2013 Loire ; ou un rouge\u00a0 AOP Hautes Cotes de Nuits Domaine Cornu \u2013 Bourgogne).<\/p>\n<p>Des boissons rafra\u00eechissantes sans alcool (Coca cola &amp; Schweppes) seront disponibles, comme le caf\u00e9 et le th\u00e9, ainsi que bien s\u00fbr de l\u2019eau min\u00e9rale (p\u00e9tillante et plate).<\/p>\n<p><b>\ud83d\udd57 Horaires <\/b>:<\/p>\n<ul>\n<li aria-level=\"1\">Embarquement \u00e0 partir de 20h00 au Port Henri IV &#8211; 75004<\/li>\n<li aria-level=\"1\">Croisi\u00e8re entre 21h30 et 00h30.<\/li>\n<li aria-level=\"1\">Soir\u00e9e dansante avec DJ de 00h30 \u00e0 02h00.<\/li>\n<\/ul>\n<p><b>\ud83d\udcb0 Prix <\/b>: \u00e0 partir de 585\u20ac<\/p>\n<p><b>\ud83d\ude0d On aime :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">La touche sucr\u00e9e de l&rsquo;infusion de f\u00e8ves de cacao, un final extra gourmand !<\/li>\n<li aria-level=\"1\">Soir\u00e9e dansante<\/li>\n<li aria-level=\"1\">La taille humaine du navire si on veut c\u00e9l\u00e9brer le r\u00e9veillon en petit comit\u00e9<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.cometoparis.com\/fre\/diner-croisiere-de-nouvel-an-a-paris-a-bord-de-l-excellence-m9000979?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Informations et r\u00e9servations<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"4-Les-Bateaux-Parisiens\"><\/span>4) Les Bateaux Parisiens<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CwPghnIIaju\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CwPghnIIaju\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Bateaux Parisiens (@bateauxparisiens)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Pour la Saint-Sylvestre, les Bateaux Parisiens vous invitent \u00e0 une soir\u00e9e festive et gastronomique, id\u00e9ale pour c\u00e9l\u00e9brer entre amis ou en famille, avec une ambiance musicale et la vue magique de Paris illumin\u00e9e.<\/p>\n<p>Le menu d\u00e9bute par des <strong>coquilles Saint-Jacques aux agrumes<\/strong>, suivies de <strong>foie gras de canard au chutney de poire<\/strong>.<\/p>\n<p>En plat, choisissez entre un <strong>bar cuit en cocotte<\/strong>, c\u00e9leri et c\u00e9leri-rave fa\u00e7on risotto, ou un <strong>filet de poulet fermier fran\u00e7ais<\/strong> avec l\u00e9gumes de saison confits, <strong>sauce Albufera et truffe noire<\/strong>.<\/p>\n<p>La soir\u00e9e se termine sur une note sucr\u00e9e, avec une cr\u00e9ation Len\u00f4tre, accompagn\u00e9e de champagne et vins comme un Champagne Jacquart et un M\u00e2con Villages, ainsi qu&rsquo;un Lussac St Emilion \u201cCh\u00e2teau Pont de Pierre\u201d.<\/p>\n<p>\ud83d\udd57 <b>Horaires <\/b>:<\/p>\n<ul>\n<li aria-level=\"1\">19h30 : Enregistrement aux pontons 5 ou 7, pied de la Tour Eiffel<\/li>\n<li aria-level=\"1\">21h00 : D\u00e9part de la croisi\u00e8re<\/li>\n<li aria-level=\"1\">00h30 : Retour \u00e0 quai, soir\u00e9e dansante jusqu\u2019\u00e0 l\u2019aube<\/li>\n<\/ul>\n<p>\ud83d\udcb0 <b>Prix <\/b>: 480 \u20ac\/personne<\/p>\n<p>\ud83d\ude0d <b>On aime<\/b> :<\/p>\n<ul>\n<li aria-level=\"1\">La vue magique<\/li>\n<li aria-level=\"1\">Le service \u00e9l\u00e9gant<\/li>\n<li aria-level=\"1\">L\u2019animation musicale<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/nouvel-an-bateaux-parisiens-1001?partner=france-hotel-guide\">Informations et r\u00e9servation<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"5-Le-Mirage\"><\/span>5) Le Mirage<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fyachts.de.paris%2Fposts%2Fpfbid0vNtwi4q77CucaUN5c7byuU5QbSZDBWxggvMN6FJ32wevNuGFEp8C8BjawWsKJoRbl&amp;show_text=false&amp;width=500\" width=\"500\" height=\"373\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Vivez une exp\u00e9rience inoubliable sur la Seine \u00e0 Paris en passant le r\u00e9veillon du Nouvel An \u00e0 bord du Mirage, un bateau \u00e9l\u00e9gant et moderne de la compagnie des <i>Yachts de Paris<\/i>.<\/p>\n<p>Contrairement \u00e0 la nostalgie que peut susciter le Paquebot, dont l\u2019allure \u00e9voque les navires d\u2019\u00e9poques, le design du Mirage est r\u00e9solument futuriste.<\/p>\n<p>Une <b>coque effil\u00e9e couleur vif argent<\/b>, un espace multim\u00e9dia high-tech calibr\u00e9 pour des <b>spectacles sons et lumi\u00e8re<\/b>, des <b>\u00e9crans plasma<\/b> et des <b>caissons lumineux<\/b> qui diffusent des images en 3D, tout y respire la modernit\u00e9.<\/p>\n<p>Et c\u2019est dans ce cadre que vous pourrez d\u00e9guster le fameux menu de la compagnie des Yachts, pr\u00e9c\u00e9demment \u00e9voqu\u00e9. Avec, tout d\u2019abord, un cocktail ap\u00e9ritif:<\/p>\n<ul>\n<li aria-level=\"1\">Comme un \u00ab\u00a0nougat\u00a0\u00bb d&rsquo;Ossau Iraty relev\u00e9 d&rsquo;un condiment \u00e0 l&rsquo;orange<\/li>\n<li aria-level=\"1\">Ravigote de c\u00e8pes, parmenti\u00e8re, vermicelles de riz frits et croustille<\/li>\n<li aria-level=\"1\">Sabl\u00e9 fleuri aux l\u00e9gumes, \u00e0 l\u2019huile d\u2019olive et au piment d&rsquo;Espelette<\/li>\n<li aria-level=\"1\">Croustille de pomme de terre parmesan au tarama et citron vert<\/li>\n<li aria-level=\"1\">Gambas marin\u00e9es \u00e0 la cardamone &amp; patate douce miell\u00e9e<\/li>\n<li aria-level=\"1\">Tartelette craquante d&rsquo;une blanquette de veau, riz pilaf<\/li>\n<\/ul>\n<p>Puis, pour passer, aux choses s\u00e9rieuses :<\/p>\n<ul>\n<li aria-level=\"1\">Entr\u00e9e : Le Saumon Fum\u00e9 marin\u00e9 \u00e0 la betterave, condiment groseille.<\/li>\n<li aria-level=\"1\">Plat : Le Veau en Mignon, c\u00e8pes au jus et \u00e9mulsion \u00e0 la truffe blanche d&rsquo;Alba<\/li>\n<li aria-level=\"1\">Dessert : \u00ab\u00a0La Cabosse\u00a0\u00bb infusion de f\u00e8ves de cacao<\/li>\n<li aria-level=\"1\">Mignardises : Macaron tout vanille Bourbon de Madagascar &amp; Cube bonbon de chocolat Len\u00f4tre<\/li>\n<\/ul>\n<p>Pour vous d\u00e9salt\u00e9rez, vous disposerez de <b>2 coupes de champagne<\/b> (par personne) Jacquard Signature, ainsi qu\u2019une <b>bouteille de vin<\/b> \u00e0 partager \u00e0 deux (un blanc, Pouilly Fum\u00e9 les Clairi\u00e8res \u2013 Loire ; ou un rouge AOP Hautes Cotes de Nuits Domaine Cornu \u2013 Bourgogne).<\/p>\n<p>Des boissons sans alcool seront disponibles.<\/p>\n<p>Apr\u00e8s votre d\u00eener, la soir\u00e9e se poursuivra ensuite par une soir\u00e9e anim\u00e9e par un DJ, qui vous fera danser jusqu\u2019\u00e0 2h du matin.<\/p>\n<p><b>\ud83d\udd57 Horaires <\/b>:<\/p>\n<ul>\n<li aria-level=\"1\">Embarquement \u00e0 partir de 20h00 au Port Henri IV &#8211; 75004<\/li>\n<li aria-level=\"1\">Croisi\u00e8re entre 21h30 et 00h30.<\/li>\n<li aria-level=\"1\">Soir\u00e9e dansante avec DJ de 00h30 \u00e0 02h00.<\/li>\n<\/ul>\n<p><b>\ud83d\udcb0 Prix<\/b> : \u00e0 partir de \u20ac 585<\/p>\n<p><b>\ud83d\ude0d On aime <\/b>:<\/p>\n<ul>\n<li aria-level=\"1\">Le menu raffin\u00e9 et vari\u00e9 avec une v\u00e9ritable farandole de propositions ap\u00e9ritives<\/li>\n<li aria-level=\"1\">Soir\u00e9e dansante<\/li>\n<li aria-level=\"1\">Le cadre chic et cosy du bateau<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.cometoparis.com\/fre\/diner-croisiere-de-nouvel-an-a-paris-a-bord-du-mirage-m9000941?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Informations et r\u00e9servations<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"6-Paris-Seine\"><\/span>6) Paris Seine<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_36336\" aria-describedby=\"caption-attachment-36336\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36336\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/paris-seine-1.jpg\" alt=\"Paris Seine\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/paris-seine-1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/paris-seine-1-475x267.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-36336\" class=\"wp-caption-text\">Le Paris Seine<\/figcaption><\/figure>\n<p>Profitez d\u2019une soir\u00e9e exceptionnelle \u00e0 bord d\u2019une p\u00e9niche confortable, le Grand Pavois, un navire majestueux aux allures de grande verri\u00e8re flottante lanc\u00e9e sur les eaux de la Seine. Ses nombreuses baies vitr\u00e9es vous garantiront une vue imprenable durant la soir\u00e9e du Nouvel An.<\/p>\n<p>En attendant le d\u00e9compte du passage \u00e0 la nouvelle ann\u00e9e jusqu\u2019\u00e0 minuit, vous d\u00e9gusterez<\/p>\n<ul>\n<li aria-level=\"1\">En entr\u00e9e, un mi-cuit de <b>foie gras<\/b>, avec du chutney de saison et des <b>noix de Saint-Jacques<\/b> snack\u00e9es, accompagn\u00e9s de <b>risotto au safran<\/b>.<\/li>\n<li aria-level=\"1\">En plat, un <b>pav\u00e9 de veau<\/b> au jus truff\u00e9, agr\u00e9ment\u00e9 d\u2019un <b>mikado de l\u00e9gumes<\/b><\/li>\n<li aria-level=\"1\">Une assiette de fromage (+8\u20ac)<\/li>\n<li aria-level=\"1\">En dessert : une gourmandise du Nouvel An que vous d\u00e9couvrirez sur place.<\/li>\n<\/ul>\n<p><b>Une coupe de champagne et une \u00bd bouteille de vin rouge (ou blanc)<\/b> vous serons offerts durant la travers\u00e9e.<\/p>\n<p>Avis aux <b>v\u00e9g\u00e9tariens<\/b>, un menu \u00e0 \u00e9t\u00e9 sp\u00e9cialement concoct\u00e9 pour vous :<\/p>\n<ul>\n<li aria-level=\"1\">En entr\u00e9e : <b>velout\u00e9 de butternuts<\/b>, ch\u00e2taignes graines de courges torr\u00e9fi\u00e9es et <b>fra\u00eecheur d&rsquo;avocat \u00e0 la mangue<\/b>, coulis de Betterave acidul\u00e9<\/li>\n<li aria-level=\"1\">En plat : Une <b>polenta<\/b> parfum\u00e9e \u00e0 la truffe, petits l\u00e9gumes de saison<\/li>\n<li aria-level=\"1\">En dessert : Une coupe de c\u0153ur Paris Seine tout chocolat<\/li>\n<\/ul>\n<p><b>\ud83d\udd57 Horaires <\/b>:<\/p>\n<ul>\n<li aria-level=\"1\">Embarquement \u00e0 partir de 20h00 au Port de Bercy<\/li>\n<li aria-level=\"1\">Croisi\u00e8re entre 21h15 et 00h15.<\/li>\n<li aria-level=\"1\">Soir\u00e9e dansante jusqu\u2019\u00e0 2h00.<\/li>\n<\/ul>\n<p><b>\ud83d\udcb0 Prix<\/b>: 430 \u20ac<\/p>\n<p><b>\ud83d\ude0d On aime<\/b> :<\/p>\n<ul>\n<li aria-level=\"1\">Un menu v\u00e9g\u00e9tarien gourmand avec une polenta parfum\u00e9e \u00e0 la truffe<\/li>\n<li aria-level=\"1\">Parking priv\u00e9 avec 60 places de stationnement.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/nouvel-an-marina-de-paris-1004?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Informations et r\u00e9servations<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"7-Le-Theo\"><\/span>7) Le Th\u00e9o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-36334\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/theo-1-1.jpg\" alt=\"Th\u00e9o\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/theo-1-1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/theo-1-1-475x267.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Passez une Saint-Sylvestre exceptionnelle dans cette p\u00e9niche intimiste aux tons bois\u00e9s chaleureux, dans une ambiance musicale, festive et gourmande.<\/p>\n<p>En montant \u00e0 bord vous pourrez profiter de la grande terrasse panoramique de ce bateau cosy et \u00e9l\u00e9gant (inhabituelle dans un navire \u00e0 taille humaine) avant d\u2019appr\u00e9cier le d\u00eener qui a \u00e9t\u00e9 concoct\u00e9 par les soins du chef de l\u2019\u00e9quipage.<\/p>\n<p>Au menu de la premi\u00e8re formule de d\u00eener-croisi\u00e8re propos\u00e9, il y aura :<\/p>\n<ul>\n<li aria-level=\"1\">Pour l\u2019ap\u00e9ritif, un cocktail du capitaine avec ou sans alcool<\/li>\n<li aria-level=\"1\">En entr\u00e9e : une belle tranche de foie gras et sa brioche fleur de sel, compot\u00e9e de figues<\/li>\n<li aria-level=\"1\">En plat : un filet mignon de veau aux morilles, mille-feuille d&rsquo;Agria \u00e0 la truffe<\/li>\n<li aria-level=\"1\">Et le chef vous surprendra par une de ses cr\u00e9ations au dessert.<\/li>\n<\/ul>\n<p>Niveau boissons, vous aurez \u00e0 disposition : 1\/2 bouteille d&rsquo;eau et de vin pour 2, ainsi qu\u2019une coupe de champagne au dessert.<\/p>\n<p>Le menu de la seconde formule de croisi\u00e8re s&rsquo;enrichit de 3 pi\u00e8ces ap\u00e9ritives et de Saint-Jacques r\u00f4ties, sauce d&rsquo;\u00e9trilles en entr\u00e9e. Et la travers\u00e9e se conclut par une soir\u00e9e dansante.<\/p>\n<p><b>\ud83d\udd57 Horaires et Prix :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">1er service, une travers\u00e9e de 2h de 18h \u00e0 20h \u00e0 199 \u20ac\n<ul>\n<li aria-level=\"2\">17h30 : Arriv\u00e9e des clients 30 min avant l\u2019\u00e9v\u00e9nement<\/li>\n<li aria-level=\"2\">18h00 : D\u00e9part du bateau en croisi\u00e8re dans Paris<\/li>\n<li aria-level=\"2\">20h00 : Retour \u00e0 quai et fin de soir\u00e9e<\/li>\n<\/ul>\n<\/li>\n<li aria-level=\"1\">2\u00e8me Service : 21h30 &#8211; 2h00 \u00e0 350 \u20ac\n<ul>\n<li aria-level=\"2\">21h00 : Arriv\u00e9e des clients 30 min avant l\u2019\u00e9v\u00e9nement<\/li>\n<li aria-level=\"2\">21h30 : D\u00e9part du bateau en croisi\u00e8re dans Paris<\/li>\n<li aria-level=\"2\">00h30 : Soir\u00e9e dansante \u00e0 quai jusqu\u2019\u00e0 2h du matin<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><b>\ud83d\ude0d On aime :\u00a0<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Tarifs plus abordables que la moyenne des croisi\u00e8res<\/li>\n<li aria-level=\"1\">Une coupe de champagne au dessert appr\u00e9ciable<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.cometoparis.com\/fre\/nouvel-an-a-paris\/bateau-le-theo-m9000897?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Informations et r\u00e9servations<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"8-Vedettes-du-Pont-Neuf\"><\/span>8) Vedettes du Pont Neuf<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_33441\" aria-describedby=\"caption-attachment-33441\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33441\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/3-bateau_henri_IV.jpg\" alt=\"Vedettes du Pont Neuf\" width=\"620\" height=\"347\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/3-bateau_henri_IV.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/3-bateau_henri_IV-475x266.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-33441\" class=\"wp-caption-text\">Vedettes du Pont Neuf<\/figcaption><\/figure>\n<p>Participez \u00e0 un d\u00eener-croisi\u00e8re dans le style des bals populaires en vous r\u00e9galant d\u2019un d\u00e9licieux repas tandis qu\u2019un duo compos\u00e9 d\u2019un <b>accord\u00e9oniste <\/b>et d\u2019une <b>chanteuse <\/b>vous fera d\u00e9couvrir ou revisitez les classiques du r\u00e9pertoire de la chanson fran\u00e7aise, avec Piaf, Yves Montand, Brassens, Brel et tant d&rsquo;autres\u2026<\/p>\n<p>Le menu est r\u00e9solument gourmand :<\/p>\n<ul>\n<li aria-level=\"1\">En entr\u00e9e, <b>foie gras<\/b> de canard et pain d\u2019\u00e9pice toast\u00e9 accompagn\u00e9 d\u2019une <b>coupe champagne<\/b><\/li>\n<li aria-level=\"1\">En plat, une souris d\u2019agneau confite avec pommes grenailles et haricots verts<\/li>\n<li aria-level=\"1\">En dessert, des macarons aux framboises enti\u00e8res et cr\u00e8me vanille<\/li>\n<\/ul>\n<p>Le tout arros\u00e9 de vin rouge (ou d\u2019eau plate si vous le souhaitez), avec une coupe de champagne servie \u00e0 l\u2019arriv\u00e9e et avant le d\u00e9compte final.<\/p>\n<p>Amis v\u00e9g\u00e9tariens, vous n\u2019avez pas \u00e9t\u00e9 oubli\u00e9s:<\/p>\n<ul>\n<li aria-level=\"1\">Vous pourrez commencer votre repas par un velout\u00e9 de ch\u00e2taignes hivernal<\/li>\n<li aria-level=\"1\">Attaquez la pi\u00e8ce de r\u00e9sistance avec un tian gratin\u00e9 aux cinq L\u00e9gumes accompagn\u00e9 de fagots de haricots<\/li>\n<li aria-level=\"1\">Et finir par des macarons aux framboises enti\u00e8res et cr\u00e8me vanille<\/li>\n<\/ul>\n<p><b>\ud83d\udd57 Horaires <\/b>:<\/p>\n<ul>\n<li aria-level=\"1\">Embarquement \u00e0 20h30 face au 19 Quai de l&rsquo;horloge, 75001 Paris (M\u00e9tro Pont Neuf)<\/li>\n<li aria-level=\"1\">D\u00e9part \u00e0 21h00<\/li>\n<li aria-level=\"1\">Arriv\u00e9e vers 00h30<\/li>\n<\/ul>\n<p><b>\ud83d\udcb0 Prix <\/b>: \u00e0 partir de 290 \u20ac<\/p>\n<p><b>\ud83d\ude0d On aime<\/b> :<\/p>\n<ul>\n<li aria-level=\"1\">Une succulente souris d\u2019agneau<\/li>\n<li aria-level=\"1\">La possibilit\u00e9 d\u2019un repas v\u00e9g\u00e9tarien<\/li>\n<li aria-level=\"1\">Le prix abordable<\/li>\n<li aria-level=\"1\">L\u2019animation musicale atypique<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.vedettesdupontneuf.com\/diner-croisiere-parisien-reveillon\/\" target=\"_blank\" rel=\"nofollow noopener\">Informations et r\u00e9servations<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Tableau-comparatif-des-diners-croisieres-du-Nouvel-An-a-Paris\"><\/span>Tableau comparatif des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div style=\"overflow-x: auto;\">\n<table>\n<tbody>\n<tr>\n<td>Bateaux<\/td>\n<td>D\u00e9part<\/td>\n<td>Dur\u00e9e<\/td>\n<td>Soir\u00e9e dansante<\/td>\n<td>Points phares du menu<\/td>\n<td>Boissons incluses<\/td>\n<td>Prix<\/td>\n<\/tr>\n<tr>\n<td><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/nouvel-an-bateaux-mouches-1002?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Bateaux Mouches<\/a><\/td>\n<td>21h00<\/td>\n<td>5h<\/td>\n<td>Oui<\/td>\n<td>Le filet de b\u0153uf Angus, accompagn\u00e9 d&rsquo;un risotto de panais au parmesan, de l\u00e9gumes croquants, ainsi que d&rsquo;une sauce aux morilles.<\/td>\n<td>\n<ul>\n<li aria-level=\"1\">1 coupe de champagne, ap\u00e9ro<\/li>\n<li aria-level=\"1\">1\/2 bouteille de vin ou de champagne<\/li>\n<li aria-level=\"1\">1\/2 bouteille d\u2019Evian ou Badoit pour 2.<\/li>\n<li aria-level=\"1\">Cognac, digestif.<\/li>\n<\/ul>\n<\/td>\n<td>460\u20ac<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\"><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/reveillon-croisiere-sur-la-seine-9000520?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Le Diamant Bleu<\/a><\/td>\n<td>18h15<\/td>\n<td>2h<\/td>\n<td><\/td>\n<td rowspan=\"2\">Le filet mignon de veau et son millefeuille d\u2019Agatha truff\u00e9<\/td>\n<td rowspan=\"2\">\n<ul>\n<li aria-level=\"1\">Cocktail (avec ou sans alcool)<\/li>\n<li aria-level=\"1\">1\/2 bouteille de vin par personne et\u00a0 d\u2019une 1\/2 bouteille d&rsquo;eau pour 2<\/li>\n<li aria-level=\"1\">Une coupe de champagne au dessert<\/li>\n<\/ul>\n<\/td>\n<td>199\u20ac<\/td>\n<\/tr>\n<tr>\n<td>21h<\/td>\n<td>5h<\/td>\n<td>Oui<\/td>\n<td>450\u20ac<\/td>\n<\/tr>\n<tr>\n<td><a href=\"https:\/\/www.cometoparis.com\/fre\/diner-croisiere-de-nouvel-an-a-paris-a-bord-de-l-excellence-m9000979?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">L\u2019Excellence<\/a><\/td>\n<td>21h30<\/td>\n<td>5h<\/td>\n<td>Oui<\/td>\n<td>Son infusion de f\u00e8ves de cacao \u00ab\u00a0La Cabosse\u00a0\u00bb<\/td>\n<td>\n<ul>\n<li aria-level=\"1\">2 coupes de champagne par personne<\/li>\n<li aria-level=\"1\">une bouteille de vin (blanc ou rouge) pour 2 personnes<\/li>\n<\/ul>\n<\/td>\n<td>585\u20ac<\/td>\n<\/tr>\n<tr>\n<td><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/nouvel-an-bateaux-parisiens-1001?partner=france-hotel-guide\">Les Bateaux Parisiens<\/a><\/td>\n<td>21h00<\/td>\n<td>3h30<\/td>\n<td>Oui<\/td>\n<td>Coquilles Saint-Jacques aux agrumes<\/td>\n<td>\n<ul>\n<li aria-level=\"1\">1 coupes de champagne par personne<\/li>\n<li aria-level=\"1\">une demi bouteille de vin (blanc ou rouge) pour 2 personnes<\/li>\n<\/ul>\n<\/td>\n<td>480\u20ac<\/td>\n<\/tr>\n<tr>\n<td><a href=\"https:\/\/www.cometoparis.com\/fre\/diner-croisiere-de-nouvel-an-a-paris-a-bord-du-mirage-m9000941?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Le Mirage<\/a><\/td>\n<td>21h30<\/td>\n<td>5h<\/td>\n<td>Oui<\/td>\n<td>Son infusion de f\u00e8ves de cacao \u00ab\u00a0La Cabosse\u00a0\u00bb<\/td>\n<td>\n<ul>\n<li aria-level=\"1\">2 coupes de champagne par personne<\/li>\n<li aria-level=\"1\">une bouteille de vin (blanc ou rouge) pour 2 personnes<\/li>\n<\/ul>\n<\/td>\n<td>580\u20ac<\/td>\n<\/tr>\n<tr>\n<td><a href=\"https:\/\/www.cometoparis.com\/fre\/catalog\/nouvel-an-marina-de-paris-1004?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Paris Seine<\/a><\/td>\n<td>21h15<\/td>\n<td>5h<\/td>\n<td>Oui<\/td>\n<td>La polenta parfum\u00e9e \u00e0 la truffe du Menu v\u00e9g\u00e9tarien<\/td>\n<td>\n<ul>\n<li aria-level=\"1\">1\/2 bouteille d\u2019eau min\u00e9rale<\/li>\n<li aria-level=\"1\">1\/2 bouteilles de vin (blanc ou rouge)<\/li>\n<\/ul>\n<\/td>\n<td>430\u20ac<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\"><a href=\"https:\/\/www.cometoparis.com\/fre\/nouvel-an-a-paris\/bateau-le-theo-m9000897?partner=france-hotel-guide\" target=\"_blank\" rel=\"nofollow noopener\">Le Th\u00e9o<\/a><\/td>\n<td>18h<\/td>\n<td>2h<\/td>\n<td><\/td>\n<td rowspan=\"2\">Le filet mignon de veau aux morilles<\/td>\n<td rowspan=\"2\">\n<ul>\n<li aria-level=\"1\">Cocktail (avec ou sans alcool)<\/li>\n<li aria-level=\"1\">1\/2 bouteille d&rsquo;eau pour 2<\/li>\n<li aria-level=\"1\">1\/2 bouteille de vin par personne<\/li>\n<li aria-level=\"1\">1 coupe de champagne au dessert<\/li>\n<\/ul>\n<\/td>\n<td>199\u20ac<\/td>\n<\/tr>\n<tr>\n<td>21h30<\/td>\n<td>5h<\/td>\n<td>Oui<\/td>\n<td>350\u20ac<\/td>\n<\/tr>\n<tr>\n<td><a href=\"https:\/\/www.vedettesdupontneuf.com\/diner-croisiere-parisien-reveillon\/\" target=\"_blank\" rel=\"nofollow noopener\">Vedettes du Pont Neuf<\/a><\/td>\n<td>21h00<\/td>\n<td>3h<\/td>\n<td><\/td>\n<td>La souris d\u2019agneau confite du menu carnivore, et le velout\u00e9 de ch\u00e2taignes du menu v\u00e9g\u00e9tarien<\/td>\n<td>\n<ul>\n<li aria-level=\"1\">Une coupe de champagne \u00e0 l&rsquo;arriv\u00e9e.<\/li>\n<li aria-level=\"1\">Une coupe de champagne au d\u00e9part.<\/li>\n<li aria-level=\"1\">Vin rouge et eau plate.<\/li>\n<\/ul>\n<\/td>\n<td>290\u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Imaginez-vous glissant sur la Seine, avec la Tour Eiffel et Notre-Dame illumin\u00e9es en toile de fond, tout en d\u00e9gustant un d\u00eener gastronomique. C&rsquo;est l&rsquo;exp\u00e9rience inoubliable &#8230; <a title=\"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s\" class=\"read-more\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/\" aria-label=\"En savoir plus sur Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":33435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-33434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Imaginez-vous glissant sur la Seine, avec la Tour Eiffel et Notre-Dame illumin\u00e9es en toile de fond, tout en d\u00e9gustant un d\u00eener gastronomique. C&rsquo;est l&rsquo;exp\u00e9rience inoubliable ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de France Hotel Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranceHotelGuide\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-05T15:55:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T17:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"347\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mona\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/\"},\"author\":{\"name\":\"Mona\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\"},\"headline\":\"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s\",\"datePublished\":\"2016-02-05T15:55:01+00:00\",\"dateModified\":\"2024-10-29T17:49:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/\"},\"wordCount\":2922,\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg\",\"articleSection\":[\"Activit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/\",\"name\":\"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg\",\"datePublished\":\"2016-02-05T15:55:01+00:00\",\"dateModified\":\"2024-10-29T17:49:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg\",\"width\":620,\"height\":347,\"caption\":\"Saint-Sylvestre r\u00e9veillon, bateau mouche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/diners-croisieres-nouvel-an-paris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"name\":\"Blog de France Hotel Guide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"France Hotel Guide\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"width\":647,\"height\":90,\"caption\":\"France Hotel Guide\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranceHotelGuide\\\/\",\"https:\\\/\\\/x.com\\\/FranceHotelGuid\",\"https:\\\/\\\/www.instagram.com\\\/francehotelguide\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\",\"name\":\"Mona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"caption\":\"Mona\"},\"description\":\"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/","og_locale":"fr_FR","og_type":"article","og_title":"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s","og_description":"Imaginez-vous glissant sur la Seine, avec la Tour Eiffel et Notre-Dame illumin\u00e9es en toile de fond, tout en d\u00e9gustant un d\u00eener gastronomique. C&rsquo;est l&rsquo;exp\u00e9rience inoubliable ... Lire plus","og_url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/","og_site_name":"Blog de France Hotel Guide","article_publisher":"https:\/\/www.facebook.com\/FranceHotelGuide\/","article_published_time":"2016-02-05T15:55:01+00:00","article_modified_time":"2024-10-29T17:49:17+00:00","og_image":[{"width":620,"height":347,"url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg","type":"image\/jpeg"}],"author":"Mona","twitter_misc":{"\u00c9crit par":"Mona","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#article","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/"},"author":{"name":"Mona","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26"},"headline":"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s","datePublished":"2016-02-05T15:55:01+00:00","dateModified":"2024-10-29T17:49:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/"},"wordCount":2922,"publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg","articleSection":["Activit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/","name":"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#primaryimage"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg","datePublished":"2016-02-05T15:55:01+00:00","dateModified":"2024-10-29T17:49:17+00:00","breadcrumb":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#primaryimage","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/39616_jean-sebastien-mouche-bateaux-mouches-nuit-hotel-de-ville.jpg","width":620,"height":347,"caption":"Saint-Sylvestre r\u00e9veillon, bateau mouche"},{"@type":"BreadcrumbList","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/diners-croisieres-nouvel-an-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le top 8 des d\u00eeners-croisi\u00e8res du Nouvel An \u00e0 Paris compar\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","name":"Blog de France Hotel Guide","description":"","publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization","name":"France Hotel Guide","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","width":647,"height":90,"caption":"France Hotel Guide"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranceHotelGuide\/","https:\/\/x.com\/FranceHotelGuid","https:\/\/www.instagram.com\/francehotelguide\/"]},{"@type":"Person","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26","name":"Mona","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","caption":"Mona"},"description":"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !"}]}},"_links":{"self":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/33434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=33434"}],"version-history":[{"count":16,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/33434\/revisions"}],"predecessor-version":[{"id":36675,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/33434\/revisions\/36675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media\/33435"}],"wp:attachment":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=33434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=33434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=33434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}