{"id":29335,"date":"2015-06-25T07:21:13","date_gmt":"2015-06-25T06:21:13","guid":{"rendered":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?p=29335"},"modified":"2022-08-25T07:21:58","modified_gmt":"2022-08-25T06:21:58","slug":"immanquables-baie-de-somme","status":"publish","type":"post","link":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/","title":{"rendered":"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme"},"content":{"rendered":"<p>La Baie de Somme est faite de lieux incontournables et d\u2019activit\u00e9s anim\u00e9es par des passionn\u00e9s. Pour un s\u00e9jour m\u00e9morable dans la r\u00e9gion, je vous ai concoct\u00e9 une liste qui saura contenter les go\u00fbts de tous en mati\u00e8re d\u2019immanquables \u00e0 voir et \u00e0 faire en Baie de Somme.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Pour les plus press\u00e9s d\u2019entre vous, voici nos recommandations en bref :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">L\u2019incontournable : <a href=\"https:\/\/www.chemindefer-baiedesomme.fr\/fr\/parcours---horaires---tarifs\" target=\"_blank\" rel=\"nofollow noopener\">le petit train de la Baie de Somme<\/a><\/li>\n<li aria-level=\"1\">Au contact de la nature : <a href=\"https:\/\/www.somme-tourisme.com\/la-baie-de-somme\/la-baie-de-somme-refuge-des-phoques\" target=\"_blank\" rel=\"nofollow noopener\">voir les phoques en baie<\/a><\/li>\n<li aria-level=\"1\">Patrimoine culturel : <a href=\"https:\/\/www.tourisme-baiedesomme.fr\/decouvrir\/abbeville-coeur-culturel\/\" target=\"_blank\" rel=\"nofollow noopener\">la ville d\u2019Abbeville<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>1) Chemin de fer de la Baie de Somme<\/h2>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fchemindeferdelabaiedesomme%2Fphotos%2Fa.654853131362074%2F2093615974152442%2F%3Ftype%3D3&amp;show_text=false&amp;width=500\" width=\"500\" height=\"333\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Le petit train, c\u2019est le premier immanquable de la Baie de Somme.<\/p>\n<p>Dans les ann\u00e9es 70, des passionn\u00e9s d\u00e9cident de cr\u00e9er l&rsquo;association \u201cChemin de Fer de la Baie de Somme\u201d pour <b>sauver un patrimoine ferroviaire<\/b> en voie de disparition.<\/p>\n<p>Depuis, ils n\u2019ont eu de cesse de restaurer et sauvegarder les voies de chemin de fer ainsi que les <b>locomotives \u00e0 vapeur<\/b> de la baie pour proposer aux passagers des itin\u00e9raires allant du Crotoy jusqu&rsquo;\u00e0 Cayeux-sur-Mer.<\/p>\n<p>Le <b>parcours le plus embl\u00e9matique<\/b> : en une heure, laissez vous porter sur les rails <b>entre le Crotoy et Saint-Valery<\/b> pour profiter d\u2019un voyage dans le temps dans des wagons d\u2019\u00e9poque am\u00e9nag\u00e9s.<\/p>\n<p><b>\ud83e\udd70 On aime <\/b>: les diff\u00e9rents parcours et les diff\u00e9rentes gares<\/p>\n<p><b>\ud83d\ude0d On adore <\/b>: l\u2019excellent \u00e9tat des wagons et locomotives d\u2019\u00e9poque<\/p>\n<p><b>\ud83d\udcb0 Prix <\/b>: 18\u20ac\/adulte pour un trajet comment\u00e9 Le Crotoy &#8211; Saint-Valery<\/p>\n<p><a href=\"https:\/\/www.chemindefer-baiedesomme.fr\/fr\/parcours---horaires---tarifs\" target=\"_blank\" rel=\"nofollow noopener\">Billetterie, horaires et parcours du train de la Baie de Somme<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>2) Visiter la vieille ville m\u00e9di\u00e9vale de Saint-Valery<\/h2>\n<figure id=\"attachment_29338\" aria-describedby=\"caption-attachment-29338\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29338 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg\" alt=\"Porte de Nevers\" width=\"620\" height=\"404\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2-475x310.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29338\" class=\"wp-caption-text\">Vieille Ville de Saint-Valery, Porte de Nevers &#8211; Cr\u00e9dits photo : <a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.JPG\" target=\"_blank\" rel=\"nofollow noopener\">photography taken by Christophe.Finot<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/3.0\" target=\"_blank\" rel=\"nofollow noopener\">CC BY-SA 3.0<\/a>, via Wikimedia Commons<\/figcaption><\/figure>\n<p>Saint-Valery, ce n\u2019est pas seulement un joli port et une jolie vue, mais aussi un <b>endroit incontournable charg\u00e9 d\u2019histoire<\/b>.<\/p>\n<p>D\u00e9ambulez dans les ruelles m\u00e9di\u00e9vales de la vieille ville et d\u00e9couvrez la tour Harold, les remparts, et <b>la Porte Jeanne d\u2019Arc<\/b>, qui tient son nom de la Pucelle d\u2019Orl\u00e9ans qui passa par Saint-Valery alors que les Anglais l\u2019emmenaient \u00e0 Rouen.<\/p>\n<p>Depuis la ville haute, vous aurez acc\u00e8s \u00e0 un superbe panorama sur la baie et les toits, mais aussi sur le port. C\u2019est d\u2019ailleurs de l\u00e0 que Guillaume le Conqu\u00e9rant embarqua pour l\u2019Angleterre.<\/p>\n<p>Conseil de local : lorsque vous vous \u00e9loignez de la vieille ville, vous tomberez sur la Chapelle des Marins, dont le belv\u00e9d\u00e8re offre une des plus belles vues sur la baie.<\/p>\n<p><b>\ud83e\udd70 On aime <\/b>: bel \u00e9tat de conservation des monuments<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : les lieux charg\u00e9s d\u2019histoire<\/p>\n<p><b>\ud83d\udcb0 Prix <\/b>: gratuit ! Prenez simplement plaisir \u00e0 vous perdre dans les ruelles.<\/p>\n<p>&nbsp;<\/p>\n<h2>3) Sortir en bateau<\/h2>\n<p><i>Quai Perr\u00e9e, 80230 Saint-Valery-sur-Somme<\/i><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fbateaux.cdtcharcot%2Fphotos%2Fa.704367343005382%2F3787131951395557%2F%3Ftype%3D3&amp;show_text=false&amp;width=500\" width=\"500\" height=\"333\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Quoi de mieux que de <b>d\u00e9couvrir la baie depuis la mer<\/b> ?<\/p>\n<p>C\u2019est ce que proposent les capitaines Forest p\u00e8re et fils \u00e0 bord du Commandant Charcot, leur embarcation qui peut accueillir jusqu\u2019\u00e0 98 passagers. Rendez-vous sur le port de plaisance de Saint-Valery pour la billetterie et le d\u00e9part.<\/p>\n<p>Depuis la mer, c\u2019est un nouveau regard que l\u2019on porte sur les quais de Saint-Valery et les fa\u00e7ades des belles villas. <b>La beaut\u00e9 de la baie se r\u00e9v\u00e8le <\/b>et le capitaine Forest p\u00e8re, ancien p\u00eacheur, vous racontera tout ce qu\u2019il sait de l\u2019histoire du port et de la baie.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : possibilit\u00e9 de privatiser un plus petit bateau de 12 places, le P\u2019tit Charcot<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : les histoires du capitaine Forest<\/p>\n<p><b>\ud83d\udcb0 Prix<\/b> : 12\u20ac pour 40 minutes, 16\u20ac pour 1h15 au coucher de soleil<\/p>\n<p><a href=\"https:\/\/www.somme-tourisme.com\/la-baie-de-somme\/la-baie-de-somme-en-bateau\" target=\"_blank\" rel=\"nofollow noopener\">Information sur les sorties en bateau avec le Commandant Charcot<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>4) A la rencontre des phoques de la baie<\/h2>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CdTsG51oza4\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CdTsG51oza4\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Arnaud Lengignon (@decouvronslabaiedesomme)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Saviez-vous que la <b>plus grande colonie fran\u00e7aise de phoques<\/b> est install\u00e9e dans la baie de Somme ?<\/p>\n<p>Depuis la terre ferme, \u00e0 pied ou encore en kayak, une multitude de possibilit\u00e9s s\u2019offrent \u00e0 vous pour apercevoir les animaux sans les effrayer.<\/p>\n<p>Le mieux, c\u2019est encore de prendre contact avec Picardie Nature, l\u2019association qui veille sur eux, ou bien de <b>r\u00e9server une sortie avec des l\u2019un des nombreux guides<\/b> qui vous proposent de partir \u00e0 leur rencontre.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : bien souvent pour les randonn\u00e9es, pas de restrictions d\u2019\u00e2ge, toute la famille est bienvenue.<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : les guides passionn\u00e9s qui vous apprendront tout ce qu\u2019il y a \u00e0 savoir sur les phoques.<\/p>\n<p><b>\ud83d\udcb0 Prix <\/b>: autour des 15\u20ac\/adulte pour une balade \u00e0 pied, autour des 30\u20ac pour les cano\u00ebs\/kayaks (les prix varient d\u2019un guide \u00e0 un autre)<\/p>\n<p><a href=\"https:\/\/www.somme-tourisme.com\/la-baie-de-somme\/la-baie-de-somme-refuge-des-phoques\" target=\"_blank\" rel=\"nofollow noopener\">Info &amp; r\u00e9servation pour voir les phoques en baie de Somme<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>5) P\u00eache \u00e0 pied au Crotoy<\/h2>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fofficedetourismelecrotoy%2Fphotos%2Fa.555962591189985%2F5318072951645568%2F%3Ftype%3D3&amp;show_text=false&amp;width=500\" width=\"500\" height=\"497\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>C\u2019est l\u2019heure d\u2019enfiler vos bottes !<\/p>\n<p>A partir du Crotoy, vous pourrez partir en baie \u00e0 pied \u00e0 mar\u00e9e basse pour partir \u00e0 <b>la p\u00eache \u00e0 la coque<\/b> (nomm\u00e9e h\u00e9non dans la r\u00e9gion). Grattez le sol avec vos r\u00e2teaux, secouez les coquillages pour les d\u00e9barrasser du sable et ramenez-les dans vos seaux.<\/p>\n<p>Et si votre proche p\u00eache n\u2019a pas \u00e9t\u00e9 des plus fructueuses, allez donc voir <b>les halles du march\u00e9 aux poissons<\/b> des quais du Crotoy. L\u00e0-bas, cinq bateaux de p\u00eache professionnels font de la vente directe de leur travail du jour.<\/p>\n<p>Attention, m\u00eame pour les particuliers, il y a des <b>r\u00e8gles \u00e0 suivre<\/b> pour ne pas mettre en danger l\u2019esp\u00e8ce. Prenez bien le temps de vous renseigner.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : une activit\u00e9 amusante \u00e0 faire en famille<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : les halles aux poissons<\/p>\n<p><b>\ud83d\udcb0 Prix<\/b> : Gratuit (sauf si vous d\u00e9cidez d\u2019acheter directement aux p\u00eacheurs de la baie)<\/p>\n<p><a href=\"https:\/\/www.comitedespeches-hautsdefrance.fr\/reglementations\/\" target=\"_blank\" rel=\"nofollow noopener\">Information et r\u00e9glementation de la p\u00eache \u00e0 pied en baie de Somme<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>6) Travers\u00e9e \u00e0 pied de la baie et d\u00e9couverte des plantes comestibles<\/h2>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fdecouvronslabaiedesomme%2Fphotos%2Fa.240531752687859%2F1660057617401925%2F%3Ftype%3D3&amp;show_text=false&amp;width=500\" width=\"500\" height=\"316\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>La baie de Somme\u2026 \u00e7a se mange ? En tout cas, ce n\u2019est ni Arnaud ni Aurore qui vous diront le contraire.<\/p>\n<p>D\u2019avril \u00e0 novembre, ces deux guides passionn\u00e9s proposent des <b>travers\u00e9es \u00e0 pied de la baie<\/b>, autant pour <b>d\u00e9couvrir l\u2019\u00e9cosyst\u00e8me<\/b> de la baie que d\u00e9couvrir les petites plantes qui se sont adapt\u00e9es au milieu salin et qui sont d\u00e9sormais utilis\u00e9es dans les recettes de la r\u00e9gion.<\/p>\n<p>Bien que leurs randonn\u00e9es soient nomm\u00e9es \u201ctravers\u00e9e de la baie \u00e0 pied\u201d et non \u201cd\u00e9couverte des plantes comestibles\u201d, pas d\u2019inqui\u00e9tude ! Arnaud et Aurore vous apprendront tout ce qu\u2019ils savent sur la baie en g\u00e9n\u00e9ral, plantes incluses.<\/p>\n<p><b>\ud83e\udd70 On aime <\/b>: d\u00e9couvrir un \u00e9cosyst\u00e8me entier<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : l\u2019\u00e9tendue des connaissances des guides qui se feront un plaisir de tout vous enseigner<\/p>\n<p><b>\ud83d\udcb0 Prix <\/b>: environ 15\u20ac\/adulte pour une travers\u00e9e de la baie<\/p>\n<p><a href=\"https:\/\/www.traversee-baiedesomme.com\/la-baie-de-somme\/les-plantes-de-la-baie-de-somme\/\" target=\"_blank\" rel=\"nofollow noopener\">R\u00e9servation travers\u00e9e de la Baie de Somme<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>7) Go\u00fbter la viande d\u2019agneau pr\u00e9 sal\u00e9<\/h2>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fphoto.php%3Ffbid%3D10160332660167340%26set%3Da.10151087609897340%26type%3D3&amp;show_text=false&amp;width=500\" width=\"500\" height=\"375\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>L\u2019appellation pr\u00e9 sal\u00e9 est une AOP qui d\u00e9signe <b>une viande d\u2019agneau broutard \u00e9lev\u00e9e en milieu salin<\/b>. La r\u00e9gion de la baie de Somme est la seule \u00e0 disposer de l\u2019appellation AOP car elle offre le cadre parfait pour une viande d\u2019exception.<\/p>\n<p>Les agneaux se nourrissent dans les pr\u00e9s-sal\u00e9s, ces \u00e9tendues de v\u00e9g\u00e9tation plane semi-noy\u00e9es dans l\u2019eau de mer. Les pr\u00e9s sont aussi connus sous le nom de \u201cmolli\u00e8res\u201d dans la r\u00e9gion. La viande produite est donc <b>unique, d\u00e9licieuse et fort en go\u00fbt<\/b>.<\/p>\n<p>Il est possible d\u2019en acheter <b>de juin \u00e0 janvier<\/b> aupr\u00e8s des \u00e9leveurs mais aussi dans les restaurants, boucheries et grandes surfaces. Faites bien attention aux \u00e9tiquettes et v\u00e9rifiez qu\u2019il s\u2019agit bien de viande AOP.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : le savoir-faire centenaire des bergers de la baie<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : la qualit\u00e9 exceptionnelle de la viande<\/p>\n<p><a href=\"https:\/\/www.agneaubaiedesomme.com\/o%C3%B9-acheter-de-l-agneau\/\" target=\"_blank\" rel=\"nofollow noopener\">Quelques producteurs de viande d\u2019agneau pr\u00e9 sal\u00e9<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>8) Le Festival de l\u2019oiseau et de la nature<\/h2>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CbNWvwfoios\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CbNWvwfoios\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Festival de l&rsquo;Oiseau (@festivaloiseaunature)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Si vous avez la chance d\u2019\u00eatre de passage dans la r\u00e9gion dans le courant du mois d\u2019avril, je vous recommande de vous pencher sur le programme du Festival de l\u2019oiseau et de la nature qui a lieu tous les ans depuis plus de 30 ans.<\/p>\n<p>Beaucoup d\u2019\u00e9v\u00e8nements et d\u2019animations sont organis\u00e9s tels que des <b>expositions<\/b>, des <b>diffusions de films animaliers<\/b>, des <b>sorties guid\u00e9es<\/b> en nature, des <b>d\u00e9bats <\/b>et m\u00eame des <b>conf\u00e9rences<\/b>.<\/p>\n<p>Un concours de photographie international a d\u2019ailleurs lieu tous les ans pour l\u2019occasion, et les photos sont affich\u00e9es sur de grands panneaux en public dans les villes de la r\u00e9gion, et sont tr\u00e8s agr\u00e9ables \u00e0 d\u00e9couvrir avec l\u2019arriv\u00e9e des beaux jours.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : la multitude d\u2019activit\u00e9s propos\u00e9es dans toute la r\u00e9gion<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : possibilit\u00e9 de participer \u00e0 des stages de photographie ouverts \u00e0 tous.<\/p>\n<p><b>\ud83d\udcb0 Prix<\/b> : Beaucoup d\u2019activit\u00e9s sont gratuites, \u00e0 l\u2019exception des diffusions de films et des sorties nature.<\/p>\n<p><a href=\"https:\/\/www.festival-oiseau-nature.com\/\" target=\"_blank\" rel=\"nofollow noopener\">Infos Festival de l\u2019oiseau et de la nature<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>9) La Maison de la Baie de Somme<\/h2>\n<p><i>D3, Le Teratu, 80230 Lanch\u00e9res<\/i><\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Cd_FFB7MChy\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/Cd_FFB7MChy\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par \u2733\ufe0f Maison Baiedesomme \u2733\ufe0f (@maisondelabaiesomme)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Anciennement Maison de l\u2019Oiseau qui proposait des spectacles avec les animaux, la Maison de la Baie de Somme est d\u00e9sormais un <b>mus\u00e9e interactif <\/b>\u00e0 propos de la faune et la flore de la baie.<\/p>\n<p>Sa d\u00e9marche s\u2019inscrit dans un but de <b>sensibilisation, d\u2019\u00e9ducation et de pr\u00e9servation de la biodiversit\u00e9 de la baie<\/b> en proposant un parcours instructif.<\/p>\n<p><b>Six salles th\u00e9matiques<\/b> vous attendent pour mieux comprendre l\u2019histoire de la baie et de ses habitants au c\u0153ur d\u2019un mus\u00e9e qui se veut tr\u00e8s interactif et ludique. Il y a \u00e9galement un <b>parcours ext\u00e9rieur<\/b> le long d\u2019une promenade pour observer les oies, les canards et autres esp\u00e8ces qui se rassemblent autour du plan d\u2019eau.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : l\u2019aspect interactif du mus\u00e9e<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : la boutique avec de nombreux produits r\u00e9gionaux et de livres locaux<\/p>\n<p><b>\ud83d\udcb0 Prix <\/b>: 9\u20ac\/adulte, 6,70\u20ac\/enfant<\/p>\n<p><a href=\"https:\/\/www.baiedesomme.fr\/lieu\/1-16-maison-de-la-baie-de-somme#nogo\" target=\"_blank\" rel=\"nofollow noopener\">Infos et r\u00e9servation pour la Maison de la Baie de Somme<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>10) Le parc du Marquenterre<\/h2>\n<p><i>25 bis Chem. des Garennes, 80120 Saint-Quentin-en-Tourmont<\/i><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fparcdumarquenterre%2Fposts%2Fpfbid0wqJyPFrAFouwcYzLDXrYEECYWYazoPbbYim64gpBQRF2Z6L6oB4ydGwFQejmfc7kl&amp;show_text=false&amp;width=500\" width=\"500\" height=\"333\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>A tous les amoureux des oiseaux, je vous donne rendez-vous au parc du Marquenterre pour les observer en vrai, dans leur habitat naturel.<\/p>\n<p>Le parc du Marquenterre, c\u2019est <b>200 hectares au c\u0153ur de la R\u00e9serve naturelle de la baie, un parcours <\/b>de 6km et 13 postes d\u2019observations pour rep\u00e9rer les oiseaux au mieux. Plusieurs boucles sont possibles pour une balade plus ou moins longue dans le but de convenir \u00e0 toute la famille.<\/p>\n<p>Vous pourrez apercevoir des oiseaux tels que la <b>spatule blanche<\/b>, l<b>\u2019avocette \u00e9l\u00e9gante<\/b>, la <b>cigogne blanche<\/b>, et beaucoup, beaucoup plus encore. En plus des oiseaux, il s\u2019agit \u00e9galement d\u2019un <b>endroit exceptionnel pour sa biodiversit\u00e9<\/b>: esp\u00e8ces v\u00e9g\u00e9tales, batraciens, insectes y cohabitent.<\/p>\n<p><b>\ud83e\udd70 On aime <\/b>: les diff\u00e9rentes boucles du parcours pour convenir \u00e0 toutes les envies et besoins.<\/p>\n<p><b>\ud83d\ude0d On adore <\/b>: observation privil\u00e9gi\u00e9e des animaux dans leur milieu naturel sans les d\u00e9ranger.<\/p>\n<p><b>\ud83d\udcb0 Prix <\/b>: 10,50\u20ac\/adulte<\/p>\n<p><a href=\"https:\/\/baiedesomme.tickeasy.com\/fr-FR\/produits\" target=\"_blank\" rel=\"nofollow noopener\">R\u00e9servation billetterie du Parc du Marquenterre\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>11) Cayeux-sur-Mer<\/h2>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CBAemFNK6Vh\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CBAemFNK6Vh\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Cayeux-sur-mer Site officiel (@cayeuxsurmer.officiel)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Cayeux-sur-Mer est situ\u00e9 au sud de l\u2019embouchure de la baie, et son endroit le plus c\u00e9l\u00e8bre, ce sont les fameuses <b>cabines de plage au nombre de 493<\/b>, qui rendent merveilleusement bien en photo, surtout au moment du coucher de soleil.<\/p>\n<p>Beaucoup d&rsquo;<b>activit\u00e9s nautiques<\/b> y sont pratiqu\u00e9es comme le kitesurf et autres sports de voile. La ville poss\u00e8de un <b>casino <\/b>non loin des cabines de la plage, et il est possible de partir \u00e0 la d\u00e9couverte de la commune <b>en v\u00e9lo<\/b> en suivant des parcours \u00e9tablis.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : le magnifique coucher de soleil sur la plage et les cabines<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : parcourir la commune en v\u00e9lo<\/p>\n<p><a href=\"https:\/\/www.somme-tourisme.com\/activites#path=commune\/CAYEUX-SUR-MER\" target=\"_blank\" rel=\"nofollow noopener\">Information et r\u00e9servation d\u2019activit\u00e9s \u00e0 Cayeux-sur-Mer<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>12) La Pointe du Hourdel<\/h2>\n<p><i>La Pointe du Hourdel, 80410 Cayeux-sur-Mer<\/i><\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CCAu7jCq9yU\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CCAu7jCq9yU\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Cayeux-sur-mer Site officiel (@cayeuxsurmer.officiel)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>La Pointe du Hourdel fait partie de la commune de Cayeux-sur-Mer et se trouve en amont de Cayeux en remontant vers la baie.<\/p>\n<p>C\u2019est l\u2019un des trois ports de la baie avec Saint-Valery et le Crotoy, et le <b>meilleur endroit pour l\u2019observation des phoques<\/b> depuis la terre ferme.<\/p>\n<p>Les jumelles sont recommand\u00e9es pour mieux apercevoir les animaux, et la meilleure option reste de donner rendez-vous \u00e0 un guide qui pourra tout vous expliquer sur les veaux marins.<\/p>\n<p>La <b>plage de galets et son phare<\/b> en fond un autre incontournable de la baie.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : l\u2019endroit parfait pour admirer les phoques de loin<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : le joli phare<\/p>\n<p><a href=\"https:\/\/www.tourisme-baiedesomme.fr\/itineraire-en-baie-de-somme\/le-hourdel\/\" target=\"_blank\" rel=\"nofollow noopener\">Plus d\u2019informations sur la Pointe du Hourdel<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>13) Ault<\/h2>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CPoKraOhTtN\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CPoKraOhTtN\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Travel photography \ud83c\udf0d (@hashtagvoyage)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Situ\u00e9e un peu plus au sud de Cayeux, la petite station baln\u00e9aire d\u2019Ault vaut le d\u00e9tour.<\/p>\n<p>Son atout charme, ce sont ses <b>magnifiques falaises<\/b> sur lesquelles sont perch\u00e9es les villas typiques de la r\u00e9gion. Il est possible d\u2019y faire de belles randonn\u00e9es, guid\u00e9es ou non, et de d\u00e9couvrir de <b>superbes panoramas<\/b>.<\/p>\n<p>En plus de ses falaises, Ault poss\u00e8de une <b>r\u00e9serve ornithologique<\/b> nomm\u00e9e le H\u00e2ble d\u2019Ault o\u00f9 des centaines d\u2019oiseaux ont \u00e9lu domicile. C\u2019est une bonne alternative aux plus grands parcs comme ceux du Marquenterre ou de Grand-Laviers.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : le phare d\u2019Ault<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : la tranquillit\u00e9 d\u2019une station baln\u00e9aire \u00e0 taille humaine<\/p>\n<p><a href=\"https:\/\/www.somme-tourisme.com\/la-baie-de-somme\/voyage-aux-falaises-de-mers-les-bains-ault\" target=\"_blank\" rel=\"nofollow noopener\">Plus d\u2019information sur Ault et ses environs<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>14) Char \u00e0 voile \u00e0 Fort-Mahon<\/h2>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fcharavoilepicardie%2Fphotos%2Fa.109444187465359%2F109445494131895%2F%3Ftype%3D3&amp;show_text=false&amp;width=500\" width=\"500\" height=\"498\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Saviez-vous que le char \u00e0 voile avait \u00e9t\u00e9 invent\u00e9 aux portes de la baie de Somme au XX\u00e8me si\u00e8cle ?<\/p>\n<p>Entre Le Crotoy et Fort-Mahon s\u2019\u00e9tend une <b>plage longue de 25 kilom\u00e8tres<\/b>, id\u00e9ale pour la pratique du char \u00e0 voile lorsque la mar\u00e9e est basse et que le sable se d\u00e9couvre.<\/p>\n<p>Apr\u00e8s la tranquillit\u00e9 d\u2019une balade en baie, il est temps pour un peu de <b>sensations fortes<\/b> ! Pas de panique, vous contr\u00f4lez la vitesse.<\/p>\n<p>Plusieurs \u00e9coles proposent des offres vari\u00e9es : initiation, randonn\u00e9es en char, etc. N\u2019h\u00e9sitez pas \u00e0 vous renseigner.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : beaucoup d\u2019initiations sont propos\u00e9es<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : les sensations fortes dans un cadre exceptionnel<\/p>\n<p><b>\ud83d\udcb0 Prix <\/b>: comptez environ 40\u20ac par adulte pour 2h<\/p>\n<p>Quelques \u00e9coles pr\u00e9sentes sur les lieux :<\/p>\n<ul>\n<li aria-level=\"1\"><a href=\"https:\/\/aerischaravoile.com\/\" target=\"_blank\" rel=\"nofollow noopener\">Ecole A\u00e9ris : informations et r\u00e9servation<\/a><\/li>\n<li aria-level=\"1\"><a href=\"https:\/\/eolia.info\/activites\/les-seances-de-char-a-voile\/\" target=\"_blank\" rel=\"nofollow noopener\">Ecole Eolia : informations et r\u00e9servation<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>15) Abbaye et Jardins de Valloires<\/h2>\n<p><i>D192 Lieu dit Valloires, 80120 Argoules<\/i><\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CAyQDD9hJH1\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CAyQDD9hJH1\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Abbaye de valloires (@abbayedevalloires)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>A moins d\u2019une trentaine de kilom\u00e8tres du Crotoy, on peut trouver l\u2019Abbaye de Valloires et ses magnifiques jardins.<\/p>\n<p>Les b\u00e2timents en eux-m\u00eames forment la <b>seule abbaye cistercienne du 18\u00e8me si\u00e8cle compl\u00e8te <\/b>de France. Au c\u0153ur des guerres du Ponthieu entre le 14\u00e8me et 17\u00e8me si\u00e8cle, utilis\u00e9e comme h\u00f4pital durant la Seconde Guerre mondiale mais \u00e9galement ayant abrit\u00e9 des enfants juifs, l\u2019histoire des lieux est riche et remonte loin dans notre histoire.<\/p>\n<p>Les <b>jardins de 8 hectares<\/b> se visitent \u00e0 l\u2019ann\u00e9e mais sont particuli\u00e8rement beaux au printemps et en \u00e9t\u00e9. Si vous \u00eates dans la r\u00e9gion au bon moment, vous aurez peut-\u00eatre la chance d\u2019admirer l\u2019<b>all\u00e9e des cerisiers en fleurs<\/b>.<\/p>\n<p><b>L\u2019\u00e9t\u00e9, un spectacle son et lumi\u00e8re est organis\u00e9<\/b> dans les jardins et l\u2019abbaye avec des projections sur des rideaux d&rsquo;eau, les murs du clo\u00eetre et la fa\u00e7ade de l\u2019abbaye. Il retrace l\u2019histoire des lieux au moyen de projections d\u2019une qualit\u00e9 visuelle et narrative exceptionnelle.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : le son et lumi\u00e8re<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : la beaut\u00e9 des jardins<\/p>\n<p><b>\ud83d\udcb0 Prix<\/b> : 8\u20ac\/personne pour une visite guid\u00e9e de l\u2019abbaye<\/p>\n<p><a href=\"https:\/\/abbaye-valloires.com\/visites-individuelles\/\" target=\"_blank\" rel=\"nofollow noopener\">Informations et r\u00e9servations pour la visite de l\u2019Abbaye et Jardins de Valloires<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>16) Le patrimoine d\u2019Abbeville<\/h2>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Bo9e-CDFacI\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/Bo9e-CDFacI\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Ville d&rsquo;Abbeville (@villedabbeville)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Si vous avez besoin de sortir les pieds du sable, pourquoi ne pas partir \u00e0 la d\u00e9couverte de la ville d\u2019<b>Abbeville et de son patrimoine culturel<\/b> ?<\/p>\n<p>Visitez l&rsquo;<b>\u00e9glise Saint-S\u00e9pulcre<\/b> et ses <b>vitraux r\u00e9alis\u00e9s par Manessier<\/b>, la <b>coll\u00e9giale Saint-Vulfran<\/b>, le <b>mus\u00e9e Boucher de Perthes<\/b> ou encore le <b>beffroi<\/b>, class\u00e9 en 2007 au patrimoine mondial de l\u2019UNESCO.<\/p>\n<p>Si la nature vous manque, le <b>parc de la Bouvaque<\/b> se fera un plaisir de vous accueillir, et si ce sont plut\u00f4t les fleurs qui vous parlent, le <b>parc d\u2019Emonville<\/b> et sa flore bien entretenue vous attendent \u00e0 c\u00f4t\u00e9 de la biblioth\u00e8que et des archives municipales.<\/p>\n<p>J\u2019oublie sans doute encore beaucoup d\u2019endroits comme le ch\u00e2teau de Bagatelle ou encore l\u2019ancien monast\u00e8re du Carmel. Abbeville, deuxi\u00e8me ville de la r\u00e9gion, poss\u00e8de un patrimoine culturel riche. N\u2019h\u00e9sitez pas et venez le d\u00e9couvrir !<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : Abbeville n\u2019est pas une ville immense, tout peut se faire \u00e0 pied<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : la diversit\u00e9 des endroits \u00e0 visiter<\/p>\n<p><b>\ud83d\udcb0 Prix<\/b> : la grande majorit\u00e9 de ces activit\u00e9s sont gratuites.<\/p>\n<p><a href=\"https:\/\/www.tourisme-baiedesomme.fr\/decouvrir\/abbeville-coeur-culturel\/\" target=\"_blank\" rel=\"nofollow noopener\">Les choses \u00e0 voir et \u00e0 faire \u00e0 Abbeville<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>17) L\u2019abbatiale de Saint-Riquier<\/h2>\n<p><i>Pl. de l&rsquo;\u00e9glise, 80135 Saint-Riquier<\/i><\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CbpY-G8oXgV\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CbpY-G8oXgV\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Une publication partag\u00e9e par Abbaye de Saint-Riquier (@abbayesaintriquier)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Si la visite de la coll\u00e9giale Saint-Vulfran d\u2019Abbeville vous a plu, alors \u00e7a vaut peut-\u00eatre le coup de continuer quelques kilom\u00e8tres plus loin pour d\u00e9couvrir l\u2019abbatiale de Saint-Riquier.<\/p>\n<p>Monument du <b>gothique flamboyant<\/b>, l\u2019abbatiale a travers\u00e9 le temps. L\u2019abbaye d\u2019origine \u00e0 laquelle elle appartenait (et dont aujourd\u2019hui il ne reste rien) aurait \u00e9t\u00e9 enti\u00e8rement <b>financ\u00e9e par Charlemagne lui-m\u00eame<\/b>. D\u00e9truite et reconstruite \u00e0 de maintes reprises, l\u2019abbatiale est d\u00e9sormais tr\u00e8s bien entretenue ainsi que ses jardins.<\/p>\n<p>L\u2019abbatiale est le monument principal du petit village et demeure un <b>lieu de vie<\/b>. Tous les \u00e9t\u00e9s, elle accueille des concerts dans le cadre du Festival de Saint-Riquier (Herv\u00e9 Niqu\u00e9, Renaud Capu\u00e7on, orchestre de Picardie, etc.), et \u00e0 sa droite se trouve le Centre Culturel de l\u2019Abbaye qui sert de mus\u00e9e.<\/p>\n<p><b>\ud83e\udd70 On aime<\/b> : la magnifique fa\u00e7ade<\/p>\n<p><b>\ud83d\ude0d On adore<\/b> : les reliques entrepos\u00e9es \u00e0 l\u2019int\u00e9rieur<\/p>\n<p><b>\ud83d\udcb0 Prix<\/b> : visite libre gratuite, 5\u20ac pour une visite comment\u00e9e de l\u2019\u00e9glise ou des jardins<\/p>\n<p><a href=\"https:\/\/www.abbaye-saint-riquier.fr\/visites.php\" target=\"_blank\" rel=\"nofollow noopener\">Information et r\u00e9servation pour la visite de l\u2019abbatiale de Saint-Riquier<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>18) La Buvette de la Plage<\/h2>\n<p><i>455 Quai Jeanne d&rsquo;Arc, 80230 Saint-Valery-sur-Somme<\/i><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FLaBuvetteDeLaPlage%2Fposts%2Fpfbid02PoeQQeubFvS3dSFXDrwugXtGXVCrVYG3LEjTk8fndPkX3tsmmv83C2LnJhD2HFAsl&amp;show_text=false&amp;width=500\" width=\"500\" height=\"375\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Mon conseil pour bien conclure vos aventures en Baie de Somme, c\u2019est de profiter d\u2019un <b>bon repas et d\u2019une belle vue<\/b>.<\/p>\n<p>Si vous suivez la promenade du Quai Jeanne d\u2019Arc de Saint-Valery jusqu\u2019au bout, vous tomberez sur la Buvette de Plage, un restaurant dont le point fort est sa <b>terrasse face \u00e0 la plage et l\u2019embouchure de la baie<\/b>.<\/p>\n<p>Pas d\u2019inqui\u00e9tude si l\u2019incontournable moules-frites ne vous convient pas, la Buvette a bien d\u2019autres plats \u00e0 sa carte pour un bon repas les pieds presque dans le sable.<\/p>\n<p><b>\ud83e\udd70 On aime <\/b>: leurs bons cocktails<\/p>\n<p><b>\ud83d\ude0d On adore <\/b>: la vue, la plage, et encore la vue!<\/p>\n<p><b>\ud83d\udcb0 Prix <\/b>: tous les plats tournent autour des 20\u20ac (entre 16 et 21\u20ac)<\/p>\n<p><a href=\"https:\/\/labuvettesaintvalery.fr\/\" target=\"_blank\" rel=\"nofollow noopener\">Plus d\u2019infos sur la Buvette de la Plage<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Baie de Somme est faite de lieux incontournables et d\u2019activit\u00e9s anim\u00e9es par des passionn\u00e9s. Pour un s\u00e9jour m\u00e9morable dans la r\u00e9gion, je vous ai &#8230; <a title=\"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme\" class=\"read-more\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/\" aria-label=\"En savoir plus sur 18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":29338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-29335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-province","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme\" \/>\n<meta property=\"og:description\" content=\"La Baie de Somme est faite de lieux incontournables et d\u2019activit\u00e9s anim\u00e9es par des passionn\u00e9s. Pour un s\u00e9jour m\u00e9morable dans la r\u00e9gion, je vous ai ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de France Hotel Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranceHotelGuide\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-25T06:21:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-25T06:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"404\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mona\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/\"},\"author\":{\"name\":\"Mona\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\"},\"headline\":\"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme\",\"datePublished\":\"2015-06-25T06:21:13+00:00\",\"dateModified\":\"2022-08-25T06:21:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/\"},\"wordCount\":3300,\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg\",\"articleSection\":[\"Province\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/\",\"name\":\"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg\",\"datePublished\":\"2015-06-25T06:21:13+00:00\",\"dateModified\":\"2022-08-25T06:21:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg\",\"width\":620,\"height\":404,\"caption\":\"Vieille Ville de Saint-Valery, Porte de Nevers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/immanquables-baie-de-somme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"name\":\"Blog de France Hotel Guide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"France Hotel Guide\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"width\":647,\"height\":90,\"caption\":\"France Hotel Guide\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranceHotelGuide\\\/\",\"https:\\\/\\\/x.com\\\/FranceHotelGuid\",\"https:\\\/\\\/www.instagram.com\\\/francehotelguide\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\",\"name\":\"Mona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"caption\":\"Mona\"},\"description\":\"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/","og_locale":"fr_FR","og_type":"article","og_title":"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme","og_description":"La Baie de Somme est faite de lieux incontournables et d\u2019activit\u00e9s anim\u00e9es par des passionn\u00e9s. Pour un s\u00e9jour m\u00e9morable dans la r\u00e9gion, je vous ai ... Lire plus","og_url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/","og_site_name":"Blog de France Hotel Guide","article_publisher":"https:\/\/www.facebook.com\/FranceHotelGuide\/","article_published_time":"2015-06-25T06:21:13+00:00","article_modified_time":"2022-08-25T06:21:58+00:00","og_image":[{"width":620,"height":404,"url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg","type":"image\/jpeg"}],"author":"Mona","twitter_misc":{"\u00c9crit par":"Mona","Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/#article","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/"},"author":{"name":"Mona","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26"},"headline":"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme","datePublished":"2015-06-25T06:21:13+00:00","dateModified":"2022-08-25T06:21:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/"},"wordCount":3300,"publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg","articleSection":["Province"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/","name":"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/#primaryimage"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg","datePublished":"2015-06-25T06:21:13+00:00","dateModified":"2022-08-25T06:21:58+00:00","breadcrumb":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/#primaryimage","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Saint-Valery-sur-Somme_-_Porte_de_Nevers_2.jpg","width":620,"height":404,"caption":"Vieille Ville de Saint-Valery, Porte de Nevers"},{"@type":"BreadcrumbList","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/immanquables-baie-de-somme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"18 immanquables \u00e0 voir et \u00e0 faire en Baie de Somme"}]},{"@type":"WebSite","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","name":"Blog de France Hotel Guide","description":"","publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization","name":"France Hotel Guide","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","width":647,"height":90,"caption":"France Hotel Guide"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranceHotelGuide\/","https:\/\/x.com\/FranceHotelGuid","https:\/\/www.instagram.com\/francehotelguide\/"]},{"@type":"Person","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26","name":"Mona","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","caption":"Mona"},"description":"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !"}]}},"_links":{"self":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/29335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=29335"}],"version-history":[{"count":5,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/29335\/revisions"}],"predecessor-version":[{"id":29774,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/29335\/revisions\/29774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media\/29338"}],"wp:attachment":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=29335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=29335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=29335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}