{"id":29235,"date":"2016-08-02T07:38:51","date_gmt":"2016-08-02T06:38:51","guid":{"rendered":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?p=29235"},"modified":"2025-11-19T16:44:31","modified_gmt":"2025-11-19T15:44:31","slug":"restaurants-entreprises-paris","status":"publish","type":"post","link":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/","title":{"rendered":"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris"},"content":{"rendered":"<p>Que ce soit pour un team building festif, un repas d&rsquo;affaire ou un repas de fin d&rsquo;ann\u00e9e, votre entreprise trouvera dans cet article les meilleurs restaurants parisiens a m\u00eame d\u2019accueillir vos collaborateurs.<\/p>\n<p>Commen\u00e7ons avec la carte pour localiser les \u00e9tablissements de notre s\u00e9lection :<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1kQxY2G3vi3ZmU3T2XWPh6uVBshDyJ0s&amp;ehbc=2E312F\" width=\"620\" height=\"480\"><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a578a7b2cbe4\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #555555;color:#555555\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #555555;color:#555555\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a578a7b2cbe4\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#Pour-les-petits-comites-%3C-100-personnes\" >Pour les petits comit\u00e9s (&lt; 100 personnes)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#Pour-les-grands-comites-%3E-100-personnes\" >Pour les grands comit\u00e9s (&gt; 100 personnes)<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Pour-les-petits-comites-%3C-100-personnes\"><\/span>Pour les petits comit\u00e9s (&lt; 100 personnes)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><b>Hanoi C\u00e0 Ph\u00ea Bercy<\/b><\/h3>\n<p><i>26 Cour Saint-Emilion, 75012 Paris<\/i><\/p>\n<p><b>Capacit\u00e9 max :<\/b> 60 personnes<\/p>\n<p><b>Type de cuisine : <\/b>Vietnamienne<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29326\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/HanoiCa\u0300Phe\u0302-.jpg\" alt=\"Hanoi C\u00e0 Ph\u00ea\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/HanoiCa\u0300Phe\u0302-.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/HanoiCa\u0300Phe\u0302--475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Hanoi C\u00e0 Ph\u00ea Bercy est un restaurant vietnamien qui propose une cuisine bas\u00e9e sur un concept chic<b> mi-bistrot <\/b>et <b>mi-caf\u00e9<\/b>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29327\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/HanoiCa\u0300Phe\u03022.jpg\" alt=\"Hanoi C\u00e0 Ph\u00ea\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/HanoiCa\u0300Phe\u03022.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/HanoiCa\u0300Phe\u03022-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>L\u2019adresse est tr\u00e8s appr\u00e9ci\u00e9e des amateurs de <b>B\u00f2 b\u00fan<\/b>, de <b>nems<\/b>, de tempura de gambas, de rouleau de printemps et d\u2019autres sp\u00e9cialit\u00e9s vietnamiennes.<\/p>\n<p><b>Prix :<\/b> \u20ac\u20ac-\u20ac\u20ac\u20ac<\/p>\n<p><b>On aime : <\/b>Les cocktails cr\u00e9ations qui m\u00ealent tout un tas de saveurs<\/p>\n<p><a href=\"https:\/\/www.privateaser.com\/lieu\/40555-hanoi-ca-phe-bercy\/soiree-entreprise\/?utm_source=francehotelguide&amp;utm_medium=affiliation\" target=\"_blank\" rel=\"nofollow noopener\">Privatisez et r\u00e9servez gratuitement une partie ou la totalit\u00e9 de l\u2019\u00e9tablissement<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Basilic Tha\u00ef<\/b><\/h3>\n<p><i>98 Bd du Montparnasse, 75014 Paris<\/i><\/p>\n<p><b>Capacit\u00e9 max :<\/b> 60 personnes<\/p>\n<p><b>Type de cuisine : <\/b>Tha\u00ef<\/p>\n<figure id=\"attachment_29315\" aria-describedby=\"caption-attachment-29315\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29315\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/basilicthai2.jpg\" alt=\"Basilic Tha\u00ef\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/basilicthai2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/basilicthai2-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29315\" class=\"wp-caption-text\">La salle situ\u00e9e devant<\/figcaption><\/figure>\n<p>Ce petit \u00e9tablissement du 14e arrondissement vous accueille dans un d\u00e9cor original et chaleureux \u00e0 l\u2019<b>ambiance d\u00e9contract\u00e9e<\/b> et <b>conviviale<\/b>.<\/p>\n<p>La cuisine tha\u00ef propos\u00e9e \u00e0 la carte r\u00e9v\u00e8le de <b>belles<\/b> et <b>subtiles saveurs<\/b>. De soupes en d\u00e9licieux rouleaux de printemps vos papilles seront imm\u00e9diatement envoy\u00e9es en <b>Tha\u00eflande<\/b>.<\/p>\n<figure id=\"attachment_29314\" aria-describedby=\"caption-attachment-29314\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29314 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/basilicthai.jpg\" alt=\"Basilic Tha\u00ef\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/basilicthai.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/basilicthai-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29314\" class=\"wp-caption-text\">La salle situ\u00e9e \u00e0 l\u2019arri\u00e8re<\/figcaption><\/figure>\n<p>C\u00f4t\u00e9 boisson, ce restaurant vous impressionnera par de <b>d\u00e9licieux cocktails<\/b>.<\/p>\n<p><i>Le petit + : <\/i>Le Basilic Tha\u00ef poss\u00e8de 2 salles pouvant recevoir respectivement 22 personnes dans la salle A et 32 dans la salle B.<\/p>\n<p><b>Prix :<\/b> \u20ac\u20ac &#8211; \u20ac\u20ac\u20ac<\/p>\n<p><b>On aime : <\/b>L\u2019adaptation de l&rsquo;\u00e9tablissement qui r\u00e9pond de mani\u00e8re personnalis\u00e9e \u00e0 vos besoins<\/p>\n<p>&nbsp;<\/p>\n<h3><b>Coquin<\/b><\/h3>\n<p><i>119 Rue des Amandiers, 75020 Paris<\/i><\/p>\n<p><b>Capacit\u00e9 max :<\/b> 30 personnes<\/p>\n<p><b>Type de cuisine :\u00a0<\/b>Fran\u00e7aise<\/p>\n<figure id=\"attachment_29316\" aria-describedby=\"caption-attachment-29316\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29316 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquin.jpg\" alt=\"coquin\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquin.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquin-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29316\" class=\"wp-caption-text\">La salle coquin<\/figcaption><\/figure>\n<p>Coquin vous accueille dans une ambiance conviviale au sein d\u2019un \u00e9tablissement m\u00ealant art d\u00e9co et modernit\u00e9.<\/p>\n<p>Leur carte de restauration de cette n\u00e9o-brasserie au cadre trendy vous propose des sp\u00e9cialit\u00e9s de <b>r\u00f4tisserie<\/b> et plats d&rsquo;inspiration <b>m\u00e9diterran\u00e9enne<\/b>. C\u00f4t\u00e9 boisson, l\u2019\u00e9quipe vous impressionnera par de <b>d\u00e9licieux cocktails<\/b>, bi\u00e8res, <b>vins<\/b> et autres spiritueux.<\/p>\n<figure id=\"attachment_29317\" aria-describedby=\"caption-attachment-29317\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29317 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquin2.jpg\" alt=\"coquin\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquin2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquin2-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29317\" class=\"wp-caption-text\">Le bar \u00e0 cocktails<\/figcaption><\/figure>\n<p>L\u2019\u00e9tablissement dispose de 2 salles :<\/p>\n<ul>\n<li aria-level=\"1\">La premi\u00e8re, qui est le bar \u00e0 cocktails, peut accueillir 20 convives<\/li>\n<li aria-level=\"1\">La deuxi\u00e8me, la salle Coquin, a une capacit\u00e9 de 30 personnes.<\/li>\n<\/ul>\n<p><b>Prix :<\/b> \u20ac<\/p>\n<p><b>On aime : <\/b>Le superbe Coq mural et les assiettes copieusement raffin\u00e9es<\/p>\n<p>&nbsp;<\/p>\n<h3><b>Nectar &#8211; Restaurant<\/b><\/h3>\n<p><i>H\u00f4tel Maison m\u00e8re, 7 Rue Mayran, 75009 Paris<\/i><\/p>\n<p><b>Capacit\u00e9 max :<\/b> 40 personnes<\/p>\n<p><b>Type de cuisine : <\/b>Street-Food gastronomique<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29320\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/nectar.jpg\" alt=\"nectar\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/nectar.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/nectar-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Nectar est un rep\u00e8re pour les bons vivants amoureux de rencontre et de partage.<\/p>\n<p>Sur les <b>banquettes confortables<\/b>, vous pourrez d\u00e9guster les plats d&rsquo;une<b> carte cr\u00e9ative<\/b>, <b>d\u00e9licate<\/b> et <b>\u00e9labor\u00e9e<\/b>, ou si vous \u00eates curieux, opter pour le menu d\u00e9couverte.<\/p>\n<p>C\u2019est un espace cosy et festif s\u2019adaptant \u00e0 toutes les envies.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29321\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/nectar2.jpg\" alt=\"nectar\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/nectar2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/nectar2-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>L\u2019\u00e9tablissement propose un concept original avec un menu du midi \u00e9volutif et un d\u00eener \u00e0 la carte avec des assiettes \u00e0 partager.<\/p>\n<p>Venez go\u00fbter des <b>recettes audacieuses<\/b> ou encore de la <b>street food<\/b> de grande qualit\u00e9.<\/p>\n<p><b>Prix :<\/b> \u20ac\u20ac-\u20ac\u20ac\u20ac<\/p>\n<p><b>On aime : <\/b>La beaut\u00e9 des plats et leurs couleurs vives<\/p>\n<p>&nbsp;<\/p>\n<h3><b>Olio e Farina<\/b><\/h3>\n<p><i>30 Quai de la Rap\u00e9e, 75012 Paris<\/i><\/p>\n<p><b>Capacit\u00e9 max :<\/b> 90 personnes<\/p>\n<p><b>Type de cuisine : <\/b>Italienne<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29324\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/oliofarina.jpg\" alt=\"Olio e Farina\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/oliofarina.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/oliofarina-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>C\u2019est dans un d\u00e9cor industriel fait de <b>b\u00e9ton cir\u00e9 <\/b>m\u00e9langeant <b>min\u00e9ral<\/b> et <b>v\u00e9g\u00e9tal<\/b>, avec une luminosit\u00e9 \u00e0 mi-chemin entre <b>chaud<\/b> et<b> froid<\/b>, que Olio et Farina vous accueillent.<\/p>\n<p>Au menu, le chef vous propose des <b>pizzas napolitaines<\/b>, des <b>p\u00e2tes<\/b> et des <b>salades<\/b> \u00e0 base d&rsquo;<b>ingr\u00e9dients italiens de qualit\u00e9<\/b>.<\/p>\n<p>Les pizzas y sont succulentes, gourmandes et traditionnellement pr\u00e9par\u00e9es avec des produits 100% Made In Italy.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29325\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/oliofarina2.jpg\" alt=\"Olio e Farina\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/oliofarina2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/oliofarina2-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>De plus, cette pizzeria dispose d\u2019une<b> grande terrasse<\/b> en face des quais qui offre un moment de <b>d\u00e9tente<\/b> durant les p\u00e9riodes ensoleill\u00e9es.<\/p>\n<p><b>Prix :<\/b> \u20ac<\/p>\n<p><b>On aime : <\/b>La qualit\u00e9 et le large choix de pizzas<\/p>\n<p>&nbsp;<\/p>\n<h3><b>Le restaurant du Break Paris<\/b><\/h3>\n<p><i>119 Bd Pereire, 75017 Paris<\/i><\/p>\n<p><b>Capacit\u00e9 max :<\/b> 50 personnes<\/p>\n<p><b>Type de cuisine : <\/b>Brunch<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29328\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak.jpg\" alt=\"Break Paris\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Le restaurant du Break Paris vous transporte de l\u2019autre c\u00f4t\u00e9 de l\u2019Atlantique avec une incroyable d\u00e9coration typiquement<b> californienne<\/b>.<\/p>\n<p>L\u2019ambiance y est conviviale et sympathique. Quant \u00e0 la carte, elle vous r\u00e9galera avec divers plats <b>copieux<\/b> et <b>savoureux<\/b>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29329\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak2.jpg\" alt=\"Break Paris\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak2-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Pour les accompagner : de la bi\u00e8re, des cocktails, du vin et plein d\u2019autres types de boissons vous attendent au<b> comptoir du bar.\u00a0<\/b><\/p>\n<p><i>Le petit + :<\/i> L\u2019\u00e9tablissement vous r\u00e9serve des prestations personnalis\u00e9es pour tout \u00e9v\u00e9nement \u00e0 organiser.<\/p>\n<p><b>Prix :<\/b> \u20ac\u20ac-\u20ac\u20ac\u20ac<\/p>\n<p><b>On aime : <\/b>La splendide d\u00e9coration californienne et la carte rafra\u00eechissante<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pour-les-grands-comites-%3E-100-personnes\"><\/span>Pour les grands comit\u00e9s (&gt; 100 personnes)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><b>Monsieur Culbuto<\/b><\/h3>\n<p><i>294 Rue des Pyr\u00e9n\u00e9es, 75020 Paris<\/i><\/p>\n<p><b>Capacit\u00e9 max :<\/b> 150 personnes<\/p>\n<p><b>Type de cuisine :\u00a0<\/b>Europ\u00e9enne<\/p>\n<figure id=\"attachment_29309\" aria-describedby=\"caption-attachment-29309\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29309\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Monsieur-Culbuto.jpg\" alt=\"Monsieur Culbuto\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Monsieur-Culbuto.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Monsieur-Culbuto-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29309\" class=\"wp-caption-text\">Les deux salles<\/figcaption><\/figure>\n<p>M\u00ealant le style <b>vintage<\/b> et moderne, le d\u00e9cor de ce restaurant de Belleville se compose d\u2019\u00e9l\u00e9ments industriels et v\u00e9g\u00e9taux qui lui conf\u00e8rent une atmosph\u00e8re <b>chill and chic<\/b>.<\/p>\n<p>Outre la possibilit\u00e9 de vous restaurer sur place, cet \u00e9tablissement vous invite \u00e9galement \u00e0 participer aux diverses animations comme le <b>Babyfoot<\/b> pour des moments privil\u00e9gi\u00e9s en compagnie de vos invit\u00e9s.<\/p>\n<figure id=\"attachment_29310\" aria-describedby=\"caption-attachment-29310\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29310 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Monsieur-Culbuto2.jpg\" alt=\"Monsieur Culbuto\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Monsieur-Culbuto2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Monsieur-Culbuto2-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29310\" class=\"wp-caption-text\">Le coin babyfoot<\/figcaption><\/figure>\n<p>La cuisine propos\u00e9e est une <b>cuisine europ\u00e9enne<\/b> m\u00ealant des saveurs<b> fran\u00e7aises<\/b>, <b>italiennes<\/b> etc..<\/p>\n<p><b>Prix :<\/b> \u20ac\u20ac<\/p>\n<p><b>On aime :<\/b> Le service qui est souvent rapide<\/p>\n<p><a href=\"https:\/\/www.privateaser.com\/lieu\/16742-monsieur-culbuto-restaurant\/soiree-entreprise\/?utm_source=francehotelguide&amp;utm_medium=affiliation\" target=\"_blank\" rel=\"nofollow noopener\">Privatisez et r\u00e9servez gratuitement une partie ou la totalit\u00e9 de l\u2019\u00e9tablissement<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>Papilla<\/h3>\n<p><i>Restaurant au 9 Rue Soufflot, 75005 Paris<\/i><\/p>\n<p><b>Capacit\u00e9 max :<\/b> 100 personnes<\/p>\n<p><b>Type de cuisine : <\/b>Italienne<\/p>\n<figure id=\"attachment_29307\" aria-describedby=\"caption-attachment-29307\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29307\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Papilla.jpg\" alt=\"Papilla\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Papilla.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Papilla-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29307\" class=\"wp-caption-text\">Le bar<\/figcaption><\/figure>\n<p>Vous le trouverez rue Soufflot, entre le Panth\u00e9on et le Jardin du Luxembourg.<\/p>\n<p>Cet \u00e9tablissement vous accueillera dans une ambiance calme et \u00e0 la fois anim\u00e9e. La d\u00e9coration y est <b>raffin\u00e9e <\/b>avec des luminaires suspendus au plafond et des <b>chandeliers <\/b>plac\u00e9s sur chaque table.<\/p>\n<p>Les baies vitr\u00e9es donnent \u00e0 la salle encore plus de clart\u00e9 et les chaises en bleu apportent une touche <b>color\u00e9e<\/b> et chaleureuse.<\/p>\n<figure id=\"attachment_29308\" aria-describedby=\"caption-attachment-29308\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29308\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Papilla2.jpg\" alt=\"Papilla\" width=\"620\" height=\"310\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Papilla2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Papilla2-475x238.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-29308\" class=\"wp-caption-text\">La salle<\/figcaption><\/figure>\n<p>La carte vous propose de profiter de menus <b>italiens<\/b> pr\u00e9par\u00e9s \u00e0 base de <b>produits frais<\/b>, de saison et de <b>d\u00e9licieux cocktails<\/b> maison.<\/p>\n<p><b>Prix :<\/b> \u20ac<\/p>\n<p><b>On aime :<\/b> Les portions TR\u00c8S g\u00e9n\u00e9reuses<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que ce soit pour un team building festif, un repas d&rsquo;affaire ou un repas de fin d&rsquo;ann\u00e9e, votre entreprise trouvera dans cet article les meilleurs &#8230; <a title=\"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris\" class=\"read-more\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/\" aria-label=\"En savoir plus sur Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":29328,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-29235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visites-gourmandes","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris\" \/>\n<meta property=\"og:description\" content=\"Que ce soit pour un team building festif, un repas d&rsquo;affaire ou un repas de fin d&rsquo;ann\u00e9e, votre entreprise trouvera dans cet article les meilleurs ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de France Hotel Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranceHotelGuide\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-02T06:38:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T15:44:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mona\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/\"},\"author\":{\"name\":\"Mona\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\"},\"headline\":\"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris\",\"datePublished\":\"2016-08-02T06:38:51+00:00\",\"dateModified\":\"2025-11-19T15:44:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/\"},\"wordCount\":1095,\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/lebreak.jpg\",\"articleSection\":[\"Gourmets\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/\",\"name\":\"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/lebreak.jpg\",\"datePublished\":\"2016-08-02T06:38:51+00:00\",\"dateModified\":\"2025-11-19T15:44:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/lebreak.jpg\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/lebreak.jpg\",\"width\":620,\"height\":310,\"caption\":\"Break Paris\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/restaurants-entreprises-paris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"name\":\"Blog de France Hotel Guide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"France Hotel Guide\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"width\":647,\"height\":90,\"caption\":\"France Hotel Guide\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranceHotelGuide\\\/\",\"https:\\\/\\\/x.com\\\/FranceHotelGuid\",\"https:\\\/\\\/www.instagram.com\\\/francehotelguide\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\",\"name\":\"Mona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"caption\":\"Mona\"},\"description\":\"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris","og_description":"Que ce soit pour un team building festif, un repas d&rsquo;affaire ou un repas de fin d&rsquo;ann\u00e9e, votre entreprise trouvera dans cet article les meilleurs ... Lire plus","og_url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/","og_site_name":"Blog de France Hotel Guide","article_publisher":"https:\/\/www.facebook.com\/FranceHotelGuide\/","article_published_time":"2016-08-02T06:38:51+00:00","article_modified_time":"2025-11-19T15:44:31+00:00","og_image":[{"width":620,"height":310,"url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak.jpg","type":"image\/jpeg"}],"author":"Mona","twitter_misc":{"\u00c9crit par":"Mona","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#article","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/"},"author":{"name":"Mona","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26"},"headline":"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris","datePublished":"2016-08-02T06:38:51+00:00","dateModified":"2025-11-19T15:44:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/"},"wordCount":1095,"publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak.jpg","articleSection":["Gourmets"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/","name":"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#primaryimage"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak.jpg","datePublished":"2016-08-02T06:38:51+00:00","dateModified":"2025-11-19T15:44:31+00:00","breadcrumb":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#primaryimage","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak.jpg","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/lebreak.jpg","width":620,"height":310,"caption":"Break Paris"},{"@type":"BreadcrumbList","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/restaurants-entreprises-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 8 restaurants pour organiser un repas entreprise \u00e0 Paris"}]},{"@type":"WebSite","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","name":"Blog de France Hotel Guide","description":"","publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization","name":"France Hotel Guide","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","width":647,"height":90,"caption":"France Hotel Guide"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranceHotelGuide\/","https:\/\/x.com\/FranceHotelGuid","https:\/\/www.instagram.com\/francehotelguide\/"]},{"@type":"Person","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26","name":"Mona","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","caption":"Mona"},"description":"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !"}]}},"_links":{"self":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/29235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=29235"}],"version-history":[{"count":13,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/29235\/revisions"}],"predecessor-version":[{"id":29363,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/29235\/revisions\/29363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media\/29328"}],"wp:attachment":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=29235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=29235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=29235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}