{"id":26503,"date":"2016-07-01T18:20:26","date_gmt":"2016-07-01T17:20:26","guid":{"rendered":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?p=26503"},"modified":"2024-04-12T10:00:54","modified_gmt":"2024-04-12T09:00:54","slug":"plats-francais-noel","status":"publish","type":"post","link":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/","title":{"rendered":"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl"},"content":{"rendered":"<p>Que retrouve-t-on sur la table des Fran\u00e7ais lors du r\u00e9veillon de No\u00ebl et le jour de No\u00ebl ? C&rsquo;est ce que nous allons voir dans cet article en passant en revue les entr\u00e9es, plats et desserts les plus embl\u00e9matiques en France les 24 et 25 d\u00e9cembre. J&rsquo;esp\u00e8re que cela vous donnera des id\u00e9es !<\/p>\n<p>Commen\u00e7ons par cette sympathique infographie pour tout visualiser d&rsquo;un seul coup :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34558\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/plats-noel-traditionnels.png\" alt=\"infographie Plats de No\u00ebl fran\u00e7ais\" width=\"800\" height=\"1500\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/plats-noel-traditionnels.png 800w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/plats-noel-traditionnels-253x475.png 253w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/plats-noel-traditionnels-546x1024.png 546w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/plats-noel-traditionnels-768x1440.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a579b26f3a4b\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #555555;color:#555555\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #555555;color:#555555\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a579b26f3a4b\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#Entrees\" >Entr\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#Plats-principaux\" >Plats principaux<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#Desserts\" >Desserts<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Entrees\"><\/span>Entr\u00e9es<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3>Les verrines<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26504\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/verrines1.jpg\" alt=\"Verrines\" width=\"619\" height=\"481\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/verrines1.jpg 619w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/verrines1-475x369.jpg 475w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/p>\n<p><b>Sal\u00e9es<\/b> ou <b>sucr\u00e9es<\/b>, les verrines savent ouvrir le repas de No\u00ebl en beaut\u00e9.<\/p>\n<p>Les Fran\u00e7ais aiment les servir en tant que hors-d&rsquo;\u0153uvre ou pour l\u2019ap\u00e9ritif, au tout d\u00e9but du repas.<\/p>\n<p>Elles sont souvent \u00e0 <b>l\u00e9gumes<\/b> et de <b>poisson<\/b> et ravissent les papilles des invit\u00e9s. <b>Avocat<\/b> et <b>saumon<\/b>, <b>crabe<\/b> et <b>pamplemousse\u2026<\/b><\/p>\n<p>C\u2019est une des entr\u00e9es qui m\u00e9lange facilement le sucr\u00e9 et le sal\u00e9 et qui se mange en quelques cuiller\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<h3>Les hu\u00eetres<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26505\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/huitres1.jpg\" alt=\"Huitres\" width=\"620\" height=\"413\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/huitres1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/huitres1-475x316.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Les assiettes <b>d\u2019hu\u00eetres<\/b> fra\u00eeches sont incontournables pour les repas de No\u00ebl.<\/p>\n<p>Elles se d\u00e9gustent la plupart du temps crues avec un filet de jus de <b>citron<\/b>.<\/p>\n<p>Et entre deux hu\u00eetres, les Fran\u00e7ais aiment croquer dans un bout de <b>pain<\/b> tartin\u00e9 de <b>beurre<\/b> doux.<\/p>\n<p>Cependant, il y a de multiples fa\u00e7ons de manger des hu\u00eetres : <b>chaudes<\/b> et cuisin\u00e9es au <b>champagne<\/b>, ou bien <b>gratin\u00e9es<\/b> au fromage.<\/p>\n<p>Ces fa\u00e7ons de les pr\u00e9parer ne font pour autant pas l\u2019unanimit\u00e9 aupr\u00e8s des Fran\u00e7ais\u2026<\/p>\n<p>C\u2019est d\u2019ailleurs difficile de plaire \u00e0 tout le monde car les hu\u00eetres sont plus ou moins <b>laiteuses<\/b>, <b>creuses<\/b> ou <b>plates<\/b>, et d\u2019un <b>calibre<\/b> plus ou moins grand\u2026<\/p>\n<p>&nbsp;<\/p>\n<h3>Le foie gras<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26506\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/foie-gras1.jpg\" alt=\"Foie gras\" width=\"620\" height=\"396\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/foie-gras1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/foie-gras1-475x303.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Bien que ce met soit controvers\u00e9 de par la fa\u00e7on dont il est produit, les Fran\u00e7ais peinent \u00e0 s\u2019en s\u00e9parer\u2026<\/p>\n<p>Le<b> foie gras<\/b> est <i>le <\/i>plat de f\u00eate par excellence.<\/p>\n<p>Comme pour une terrine ou un p\u00e2t\u00e9, il est servi en belle <b>tranche<\/b> g\u00e9n\u00e9reuse et se d\u00e9guste sur du <b>pain grill\u00e9<\/b>.<\/p>\n<p>Il s\u2019accompagne souvent de <b>chutney<\/b> ou compote de fruits, le plus souvent de <b>figues<\/b>, ainsi qu\u2019un verre de <b>champagne<\/b> ou d\u2019un <b>vin blanc moelleux<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<h3>Le plateau de fruit de mer<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26507\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/fruit-de-mer1.jpg\" alt=\"plateau de fruit de mer\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/fruit-de-mer1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/fruit-de-mer1-475x267.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Langoustines, pinces de crabes, crevettes, bulots, bigorneaux, c\u2019est ce qui compose habituellement le <b>plateau de fruits de mer<\/b>.<\/p>\n<p>Cette entr\u00e9e est tr\u00e8s populaire en France et convient \u00e0 beaucoup de par la vari\u00e9t\u00e9 de <b>crustac\u00e9s<\/b> \u00e0 d\u00e9guster.<\/p>\n<p>Mais ce que beaucoup pr\u00e9f\u00e8rent, c\u2019est la <b>mayonnaise<\/b> maison qui l\u2019accompagne.<\/p>\n<p>Les Fran\u00e7ais trempent la chair fra\u00eeche d\u2019une langoustine dans la mayonnaise et l&rsquo;engloutissent sans plus de c\u00e9r\u00e9monie !<\/p>\n<p>&nbsp;<\/p>\n<h3>Les escargots<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26508\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/escargots1.jpg\" alt=\"Escargots persill\u00e9s\" width=\"620\" height=\"412\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/escargots1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/escargots1-475x316.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Les escargots est l\u2019un des plats qui repr\u00e9sente la <b>cuisine fran\u00e7aise \u00e0 l\u2019\u00e9tranger<\/b>.<\/p>\n<p>Pourtant, les Fran\u00e7ais n\u2019en mangent pas si souvent. C\u2019est un met pour les occasions sp\u00e9ciales.<\/p>\n<p>Ainsi, il se pr\u00eate parfaitement pour l\u2019entr\u00e9e du repas de No\u00ebl. L&rsquo;escargot le plus connu et appr\u00e9ci\u00e9 est le c\u00e9l\u00e8bre escargot de <b>Bourgogne<\/b>.<\/p>\n<p>Ils se pr\u00e9parent g\u00e9n\u00e9ralement au <b>beurre persill\u00e9<\/b> et \u00e0 <b>l\u2019ail<\/b> mais les Fran\u00e7ais redoublent de cr\u00e9ativit\u00e9 et les cuisinent \u00e9galement en fricass\u00e9e ou encore en feuillet\u00e9.<\/p>\n<p>Comme pour des <b>bigorneaux<\/b> et <b>bulots<\/b>, il faut d\u00e9nicher l\u2019escargot de sa cachette avec une fourchette ou un pic adapt\u00e9 avant de pouvoir le savourer !<\/p>\n<p>&nbsp;<\/p>\n<h3>Le saumon fum\u00e9<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26509\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/saumon-fume1.jpg\" alt=\"Saumon fum\u00e9\" width=\"620\" height=\"413\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/saumon-fume1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/saumon-fume1-475x316.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Et oui, le <b>saumon<\/b> <b>fum\u00e9<\/b> est aussi tr\u00e8s populaire en France !<\/p>\n<p>Accompagn\u00e9 d\u2019une <b>sauce aneth <\/b>ou ciboulette, il se d\u00e9vore d\u2019une bouch\u00e9e.<\/p>\n<p>\u00c0 d\u00e9poser sur des <b>blinis<\/b> ou des <b>toasts<\/b> grill\u00e9s, il peut \u00e9galement se retrouver cuisin\u00e9 avec un \u0153uf \u00e0 la coque, ou en petit burger pour l\u2019ap\u00e9ritif.<\/p>\n<p>&nbsp;<\/p>\n<h3>Les coquilles Saint-Jacques<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33596 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquilles-saint-jacques-1.jpg\" alt=\"Coquilles Saint-Jacques\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquilles-saint-jacques-1.jpg 750w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/coquilles-saint-jacques-1-475x317.jpg 475w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Symbole de finesse et de festivit\u00e9, les Coquilles Saint-Jacques sont une entr\u00e9e pris\u00e9e lors du r\u00e9veillon.<\/p>\n<p>Elles sont appr\u00e9ci\u00e9es pour leur <strong>texture d\u00e9licate et leur go\u00fbt subtil<\/strong>.<\/p>\n<p>Les Saint-Jacques peuvent \u00eatre servies simplement<strong> po\u00eal\u00e9es avec du beurre et du persil<\/strong>, ou pr\u00e9sent\u00e9es <strong>en gratin<\/strong>, napp\u00e9es d\u2019une sauce cr\u00e9meuse et gratin\u00e9es au four.<\/p>\n<p>Elles sont aussi parfois accompagn\u00e9es d&rsquo;une pur\u00e9e de panais ou de c\u00e9leri, ajoutant une touche terreuse et douce au plat.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Plats-principaux\"><\/span>Plats principaux<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3>La dinde aux marrons<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26510\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/dinde1.jpg\" alt=\"dinde aux marrons\u00a0\" width=\"620\" height=\"413\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/dinde1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/dinde1-475x316.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>C\u2019est le plat <b>traditionnel<\/b> de No\u00ebl en France.<\/p>\n<p>Une farce est d\u2019abord pr\u00e9par\u00e9e \u00e0 base de <b>chair<\/b> <b>\u00e0 saucisse, mie de pain, marrons<\/b> avant d\u2019\u00eatre assaisonn\u00e9e et de servir \u00e0 remplir la <b>dinde<\/b>.<\/p>\n<p>La dinde dore au four pendant plus d\u2019une heure avant d\u2019\u00eatre servie encore fumante.<\/p>\n<p>C\u2019est presque deux plats en un, une farce d\u00e9licieusement juteuse et une <b>volaille<\/b> \u00e0 la peau croustillante et la tendre chair !<\/p>\n<p>La composition de la farce s\u2019adapte \u00e0 tous les go\u00fbts comme pour la f<b>arce aux champignons ou la farce aux pommes.<\/b><\/p>\n<p>&nbsp;<\/p>\n<h3>La volaille<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26511\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/poulet1.jpg\" alt=\"Poulet\" width=\"620\" height=\"408\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/poulet1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/poulet1-475x313.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Cependant, une dinde enti\u00e8re pesant autour de 6 kg et le prix au kilo gravitant entre 13 et 23 euros, c\u2019est un met qui en a pour votre argent !<\/p>\n<p>Les Fran\u00e7ais optent alors pour des solutions plus abordables telles que la <b>pintade, la poularde, le chapon ou simplement le poulet <\/b>!<\/p>\n<p>Cela d\u00e9pend \u00e9galement du nombre d\u2019invit\u00e9s, l\u2019oie reste la plus grosse des volailles et remplira largement plus de 6 assiettes.<\/p>\n<p>&nbsp;<\/p>\n<h3>Le gibier<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33595 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/sanglier-1.jpg\" alt=\"gibier (sanglier)\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/sanglier-1.jpg 750w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/sanglier-1-475x317.jpg 475w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Le gibier est une part essentielle de la tradition culinaire fran\u00e7aise, particuli\u00e8rement pendant les f\u00eates de No\u00ebl. Cela inclut le <strong>cerf<\/strong>, le <strong>sanglier<\/strong>, et parfois le <strong>faisan<\/strong>.<\/p>\n<p>Ces viandes riches et savoureuses sont souvent pr\u00e9par\u00e9es <strong>en r\u00f4tis ou en civets<\/strong>, mijot\u00e9es lentement avec des vins robustes et des herbes aromatiques.<\/p>\n<p>La complexit\u00e9 de leurs saveurs se marie parfaitement avec les garnitures hivernales comme les pur\u00e9es de l\u00e9gumes racines ou les choux brais\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<h3>Le magret de canard<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33597 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/magret.jpg\" alt=\"magret de canard\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/magret.jpg 750w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/magret-475x317.jpg 475w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Ce<strong> filet de<\/strong> <strong>canard<\/strong>, souvent servi ros\u00e9, offre une<strong> chair tendre et juteuse<\/strong>.<\/p>\n<p>Il est g\u00e9n\u00e9ralement <strong>po\u00eal\u00e9<\/strong> et accompagn\u00e9 de sauces sucr\u00e9es-sal\u00e9es, comme une r\u00e9duction au miel et au vinaigre balsamique ou une sauce aux fruits rouges.<\/p>\n<p>Ce plat raffin\u00e9 se marie \u00e0 merveille avec des accompagnements simples comme des pommes de terre saut\u00e9es ou une po\u00eal\u00e9e de l\u00e9gumes de saison.<\/p>\n<p>&nbsp;<\/p>\n<h3>Le gratin dauphinois<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26512\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/potato-casserole-g969a0ba48_6401.jpg\" alt=\"Gratin dauphinois\" width=\"620\" height=\"523\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/potato-casserole-g969a0ba48_6401.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/potato-casserole-g969a0ba48_6401-475x401.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Mais alors, qu\u2019est-ce qui accompagne ces d\u00e9licieuses volailles ?<\/p>\n<p>Le plus souvent, ce sont les <b>pommes de terre<\/b>, et surtout celles cuisin\u00e9es en <b>gratin<\/b> <b>dauphinois<\/b> !<\/p>\n<p>D\u00e9coup\u00e9es en rondelles fines, elles cuisent au four pendant une heure dans un appareil \u00e0 base de lait, muscade et ail.<\/p>\n<p>Petits et grands en raffolent.<\/p>\n<p>&nbsp;<\/p>\n<h3>Les pomme-de-terres saut\u00e9es<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26513\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/patate-sautees1.jpg\" alt=\"Pomme-de-terres saut\u00e9es\" width=\"620\" height=\"413\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/patate-sautees1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/patate-sautees1-475x316.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Simplement coup\u00e9es en d\u00e9s et rissol\u00e9es dans une po\u00eale jusqu\u2019\u00e0 ce qu\u2019elles soient dor\u00e9es et luisantes, c\u2019est \u00e9galement l\u2019accompagnement pomme-de-terre pr\u00e9f\u00e9r\u00e9 des Fran\u00e7ais.<\/p>\n<p>&nbsp;<\/p>\n<h3>Pur\u00e9es<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26514\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/puree1.jpg\" alt=\"Pur\u00e9e de pomme de terre\" width=\"620\" height=\"465\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/puree1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/puree1-475x356.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Encore une fois, cela reste la pomme-de-terre qui remporte la pur\u00e9e pr\u00e9f\u00e9r\u00e9e \u00e0 No\u00ebl.<\/p>\n<p>Cependant, la <b>patate douce<\/b> apporte un peu de changement avec son c\u00f4t\u00e9 sucr\u00e9.<\/p>\n<p>Les pur\u00e9es de <b>carottes<\/b> ou de <b>c\u00e9leri<\/b> sont appr\u00e9ci\u00e9es avec la volaille r\u00f4tie au four.<\/p>\n<p>Parfois m\u00eame, c\u2019est un <b>floril\u00e8ge<\/b> de diff\u00e9rentes pur\u00e9es qui servent <b>d\u2019accompagnement<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<h3>Les champignon grill\u00e9s<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26515\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/champignons.jpg\" alt=\"champignons\" width=\"620\" height=\"414\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/champignons.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/champignons-475x317.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Les amateurs de champignons sont souvent ravis de trouver une po\u00eal\u00e9e de champignons en guise d\u2019accompagnement.<\/p>\n<p><b>C\u00e8pes, girolles, champignons de Paris<\/b>, ou bien champignons d\u2019une cueillette r\u00e9ussie, tout se pr\u00eate pour une <b>po\u00eal\u00e9e<\/b> aux diff\u00e9rents parfums.<\/p>\n<p>Bien qu\u2019on retrouve souvent des champignons dans la farce qui compl\u00e8te la volaille, rien n\u2019emp\u00eache les Fran\u00e7ais d\u2019en rajouter une louche !<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Desserts\"><\/span>Desserts<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3>B\u00fbches<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26516\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel.jpg\" alt=\"B\u00fbches de No\u00ebl\" width=\"620\" height=\"412\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel-475x316.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>La b\u00fbche est le dessert des f\u00eates d\u2019hiver mais surtout de No\u00ebl.<\/p>\n<p>Qu&rsquo;elle soit <b>glac\u00e9e<\/b> ou non, elle est principalement \u00e0 base de <b>chocolat<\/b> ou aux <b>fruits<\/b>.<\/p>\n<p>C\u2019est une p\u00e2te \u00e0 <b>biscuit<\/b> cuite sur laquelle est \u00e9tal\u00e9e du <b>chocolat<\/b>, de la <b>confiture<\/b>, ou d&rsquo;autres garnitures plus ou moins fantaisistes.<\/p>\n<p>Ensuite, cette p\u00e2te est roul\u00e9e pour former une b\u00fbche de gourmandise et coup\u00e9e en tranches pour que tout le monde ait sa part !<\/p>\n<p>Elle est parfaite car elle s&rsquo;adapte \u00e0 tous les go\u00fbts et le biscuit peut \u00eatre lui aussi parfum\u00e9.<\/p>\n<p>Les b\u00fbches glac\u00e9es sont n\u00e9anmoins tr\u00e8s populaires car l\u00e9g\u00e8rement plus <b>l\u00e9g\u00e8res<\/b> apr\u00e8s un repas tel que celui de No\u00ebl.<\/p>\n<p>&nbsp;<\/p>\n<h3>P\u00e2tisseries<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26517\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/paris-brest1.jpg\" alt=\"Paris Brest\" width=\"620\" height=\"414\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/paris-brest1.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/paris-brest1-475x317.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>No\u00ebl c\u2019est \u00e9galement l\u2019occasion de savourer des <b>p\u00e2tisseries<\/b> que l&rsquo;on ne s&rsquo;autorise que pour les grandes occasions.<\/p>\n<p>Les p\u00e2tisseries pr\u00e9f\u00e9r\u00e9es des Fran\u00e7ais sont le <b>g\u00e2teau au chocolat<\/b> et les<b> tartes aux fruits<\/b>, mais ne sont s\u00fbrement pas consid\u00e9r\u00e9es assez \u201cchics\u201d pour un repas de No\u00ebl.<\/p>\n<p>Alors, place aux p\u00e2tisseries tel que le <b>Paris-Brest, le Mille-feuille<\/b> ou autre composition du p\u00e2tissier du coin.<\/p>\n<p>&nbsp;<\/p>\n<h3>Glaces<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26518\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/glace.jpg\" alt=\"Glace\" width=\"620\" height=\"356\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/glace.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/glace-475x273.jpg 475w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Pour finir un repas d\u00e9j\u00e0 bien lourd pour l\u2019estomac, la glace s\u2019av\u00e8re \u00eatre le p\u00e9ch\u00e9-mignon des Fran\u00e7ais.<\/p>\n<p>D\u2019autant plus que chacun peut choisir sa <b>saveur<\/b> pr\u00e9f\u00e9r\u00e9e et il y a souvent l\u2019embarras du choix !<\/p>\n<p><b>Vanille, chocolat, pistache, citron, mangue, fruits de la passion<\/b>\u2026 la liste est interminable !<\/p>\n<p>Des petits biscuits s\u2019y ajoutent souvent comme les <b>cigarettes<\/b> <b>russes ou les sp\u00e9culoos.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que retrouve-t-on sur la table des Fran\u00e7ais lors du r\u00e9veillon de No\u00ebl et le jour de No\u00ebl ? C&rsquo;est ce que nous allons voir dans &#8230; <a title=\"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl\" class=\"read-more\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/\" aria-label=\"En savoir plus sur 18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":26516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-26503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visites-gourmandes","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl\" \/>\n<meta property=\"og:description\" content=\"Que retrouve-t-on sur la table des Fran\u00e7ais lors du r\u00e9veillon de No\u00ebl et le jour de No\u00ebl ? C&rsquo;est ce que nous allons voir dans ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de France Hotel Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranceHotelGuide\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-01T17:20:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T09:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mona\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/\"},\"author\":{\"name\":\"Mona\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\"},\"headline\":\"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl\",\"datePublished\":\"2016-07-01T17:20:26+00:00\",\"dateModified\":\"2024-04-12T09:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/\"},\"wordCount\":1632,\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/buche-a-noel.jpg\",\"articleSection\":[\"Gourmets\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/\",\"name\":\"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/buche-a-noel.jpg\",\"datePublished\":\"2016-07-01T17:20:26+00:00\",\"dateModified\":\"2024-04-12T09:00:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/buche-a-noel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/buche-a-noel.jpg\",\"width\":620,\"height\":412,\"caption\":\"B\u00fbches de No\u00ebl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/plats-francais-noel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"name\":\"Blog de France Hotel Guide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"France Hotel Guide\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"width\":647,\"height\":90,\"caption\":\"France Hotel Guide\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranceHotelGuide\\\/\",\"https:\\\/\\\/x.com\\\/FranceHotelGuid\",\"https:\\\/\\\/www.instagram.com\\\/francehotelguide\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\",\"name\":\"Mona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"caption\":\"Mona\"},\"description\":\"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/","og_locale":"fr_FR","og_type":"article","og_title":"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl","og_description":"Que retrouve-t-on sur la table des Fran\u00e7ais lors du r\u00e9veillon de No\u00ebl et le jour de No\u00ebl ? C&rsquo;est ce que nous allons voir dans ... Lire plus","og_url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/","og_site_name":"Blog de France Hotel Guide","article_publisher":"https:\/\/www.facebook.com\/FranceHotelGuide\/","article_published_time":"2016-07-01T17:20:26+00:00","article_modified_time":"2024-04-12T09:00:54+00:00","og_image":[{"width":620,"height":412,"url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel.jpg","type":"image\/jpeg"}],"author":"Mona","twitter_misc":{"\u00c9crit par":"Mona","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#article","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/"},"author":{"name":"Mona","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26"},"headline":"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl","datePublished":"2016-07-01T17:20:26+00:00","dateModified":"2024-04-12T09:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/"},"wordCount":1632,"publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel.jpg","articleSection":["Gourmets"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/","name":"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#primaryimage"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel.jpg","datePublished":"2016-07-01T17:20:26+00:00","dateModified":"2024-04-12T09:00:54+00:00","breadcrumb":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#primaryimage","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel.jpg","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/buche-a-noel.jpg","width":620,"height":412,"caption":"B\u00fbches de No\u00ebl"},{"@type":"BreadcrumbList","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/plats-francais-noel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"18 plats traditionnels et iconiques fran\u00e7ais mang\u00e9s \u00e0 No\u00ebl"}]},{"@type":"WebSite","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","name":"Blog de France Hotel Guide","description":"","publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization","name":"France Hotel Guide","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","width":647,"height":90,"caption":"France Hotel Guide"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranceHotelGuide\/","https:\/\/x.com\/FranceHotelGuid","https:\/\/www.instagram.com\/francehotelguide\/"]},{"@type":"Person","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26","name":"Mona","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","caption":"Mona"},"description":"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !"}]}},"_links":{"self":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/26503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=26503"}],"version-history":[{"count":9,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/26503\/revisions"}],"predecessor-version":[{"id":34559,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/26503\/revisions\/34559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media\/26516"}],"wp:attachment":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=26503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=26503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=26503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}