{"id":21354,"date":"2015-03-08T13:37:19","date_gmt":"2015-03-08T12:37:19","guid":{"rendered":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?p=21354"},"modified":"2021-07-23T13:38:10","modified_gmt":"2021-07-23T12:38:10","slug":"que-faire-a-strasbourg","status":"publish","type":"post","link":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/","title":{"rendered":"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg"},"content":{"rendered":"<figure id=\"attachment_21356\" aria-describedby=\"caption-attachment-21356\" style=\"width: 630px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21356\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1.jpg\" alt=\"strasbourg\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1.jpg 640w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1-475x316.jpg 475w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-21356\" class=\"wp-caption-text\">Strasbourg<\/figcaption><\/figure>\n<p>Bord\u00e9e par le Rhin, la ville de Strasbourg est une ville calme qui a su garder son charme d&rsquo;antan. Lors de votre visite, vous serez surpris par le m\u00e9lange culturel qui y r\u00e8gne, une ville \u00e0 mi-chemin entre la France et l&rsquo;Allemagne. Une ville qui est \u00e9galement en pleine mutation entre anciennet\u00e9 et modernit\u00e9.<\/p>\n<p>Le patrimoine historique et culturel de cette ville vous propose de nombreuses visites. N\u00e9anmoins, comme il n&rsquo;est pas toujours facile de savoir quoi visiter quand on ne connait pas, je vous propose ma s\u00e9lection de lieux et de choses \u00e0 faire \u00e0 Strasbourg.<\/p>\n<p>&nbsp;<\/p>\n<h2>1) Cath\u00e9drale Notre-Dame de Strasbourg<\/h2>\n<p><em>Place de la Cath\u00e9drale<br \/>\n<\/em><br \/>\n<img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_cathedrale.jpg\" alt=\"Cath\u00e9drale\" \/><\/p>\n<p>La cath\u00e9drale de Strasbourg est le symbole de la ville: avec ses 140 m\u00e8tres de haut, il est difficile de rater l&rsquo;\u00e9difice.<\/p>\n<p>Cette imposante construction fait la renomm\u00e9e de la ville \u00e0 travers toute la France, et s&rsquo;il ne fallait retenir qu&rsquo;une visite \u00e0 faire dans Strasbourg, sa cath\u00e9drale s&rsquo;impose comme le candidat parfait.<\/p>\n<p>Elle est un v\u00e9ritable t\u00e9moin de l&rsquo;histoire de la ville, \u00e0 travers son architecture gothique, ses nombreuses sculptures datant pour la plupart du 15e si\u00e8cle et sa crypte du 11e si\u00e8cle.<\/p>\n<p>Ce monument fut pendant plus de deux si\u00e8cles, de 1647 \u00e0 1874, le plus haut \u00e9difice du monde et est encore aujourd&rsquo;hui la 2\u00e8me cath\u00e9drale la plus grande de France apr\u00e8s celle de Rouen.<\/p>\n<p>A l\u2019int\u00e9rieur, vous trouverez des visites guid\u00e9es mais aussi une horloge astronomique et vous pourrez m\u00eame, pour les plus courageux et pour ceux qui n&rsquo;ont pas peur du vide, gravir les 332 marches du clocher de la cath\u00e9drale.<\/p>\n<p>L\u00e0-haut, vous aurez acc\u00e8s \u00e0 une plateforme panoramique culminant \u00e0 66 m\u00e8tres de hauteur, qui vous offrira la plus belle vue sur Strasbourg.<\/p>\n<p>Un monument \u00e0 d\u00e9couvrir ! Victor Hugo ne tarissait pas d&rsquo;\u00e9loges \u00e0 son sujet, il disait qu&rsquo;elle repr\u00e9sentait le \u00ab\u00a0prodige du gigantesque et du d\u00e9licat\u00a0\u00bb.<\/p>\n<p><strong>Notre conseil :<\/strong> Montez sur la plate-forme panoramique (payante mais peu ch\u00e8re) pour profiter de la vue sur Strasbourg<\/p>\n<p>&nbsp;<\/p>\n<h2>2) La Petite France<\/h2>\n<p><img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_petite_france.jpg\" alt=\"Petite France\" \/><\/p>\n<p>Voici un quartier incontournable ici \u00e0 Strasbourg, l\u2019un des quartiers, si ce n&rsquo;est LE quartier le plus connu de la ville, et pour cause : il en est le plus typique.<\/p>\n<p>Avec ses maisons \u00e0 colombages et ses petits canaux, il tranche litt\u00e9ralement avec le reste de Strasbourg, plus moderne.<\/p>\n<p>C\u2019est le quartier le plus pittoresque du vieux Strasbourg.<\/p>\n<p>Les p\u00eacheurs, les meuniers et les tanneurs vivaient et travaillaient autrefois ici. Situ\u00e9 sur la Grande Ile de Strasbourg, il a \u00e9t\u00e9 b\u00e2ti \u00e0 fleur d&rsquo;eau, ce qui offre au quartier de magnifiques canaux, o\u00f9 il fait bon se balader.<\/p>\n<p>Les maisons \u00e0 colombages datent, pour les plus anciennes, du 16e si\u00e8cle.<\/p>\n<p>La Petite France est un lieu hors du temps : ici tout est fait pour sauvegarder cette ambiance, ce qui en fait un lieu de pr\u00e9dilection des touristes.<\/p>\n<p>C\u2019est un quartier incontournable de Strasbourg: vous auriez tort de le louper!<\/p>\n<p><strong>Notre conseil<\/strong> : Attention aux attrape-touristes<\/p>\n<p>&nbsp;<\/p>\n<h2>3) Mus\u00e9e alsacien<\/h2>\n<p><em>23-25 Quai Saint-Nicolas<\/em><\/p>\n<p><img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_musee_alsacien.jpg\" alt=\"Mus\u00e9e Alsacien\" \/><\/p>\n<p>Le Mus\u00e9e Alsacien est un mus\u00e9e d\u2019art et de traditions populaires, il vous accueille pour vous faire d\u00e9couvrir l&rsquo;ancienne vie strasbourgeoise.<\/p>\n<p>Ainsi, lors de votre visite, vous pourrez d\u00e9couvrir des milliers d&rsquo;objets t\u00e9moins de la vie rurale de la r\u00e9gion Alsace-Lorraine du 18e au 20e si\u00e8cle.<\/p>\n<p>Vous pourrez admirer des costumes et autres v\u00eatements d&rsquo;\u00e9poque, aussi bien des habits de paysans, que les habits des classes sociales plus ais\u00e9es.<\/p>\n<p>Vous trouverez \u00e9galement des meubles d&rsquo;\u00e9poque, des jouets, des imageries, qui vous feront revivre le quotidien d&rsquo;une famille \u00e0 l&rsquo;heure du souper, par exemple.<\/p>\n<p>Le point de vue ne se limite pas \u00e0 la vie dans la ville de Strasbourg: au cours de la visite, c&rsquo;est tout le \u00ab\u00a0pays\u00a0\u00bb d&rsquo;Alsace que l&rsquo;on d\u00e9couvre, des plaines agricoles aux montagnes vosgiennes.<\/p>\n<p>Le Mus\u00e9e Alsacien propose donc aux visiteurs un parcours plein de charme \u00e0 travers d\u2019anciennes demeures strasbourgeoises reli\u00e9es par des escaliers et des coursives en bois.<\/p>\n<p>Le visiteur explore ce mus\u00e9e attentif au moindre d\u00e9tail, d\u00e9tails de la vie courante qui donnent la sensation que la maison vient d&rsquo;\u00eatre d\u00e9sert\u00e9e par ses habitants.<\/p>\n<p>Le mus\u00e9e vous offre une v\u00e9ritable parenth\u00e8se hors du temps et vous fait voyager dans le pass\u00e9.<\/p>\n<p><strong>Notre conseil<\/strong> : Assister \u00e0 la visite guid\u00e9e n\u2019est pas n\u00e9cessaire.<\/p>\n<p>Pour toute information sur le Mus\u00e9e Alsacien : <a href=\"https:\/\/www.musees.strasbourg.eu\/\" target=\"_blank\" rel=\"nofollow noopener\">http:\/\/www.musees.strasbourg.eu\/<br \/>\n<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>4) Faites une sortie familiale au Vaisseau<\/h2>\n<p><em>1 Bis Rue Philippe Dollinger<br \/>\n<\/em><br \/>\n<img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_vaisseau.jpg\" alt=\"Le Vaisseau\" \/><\/p>\n<p>Le concept du Vaisseau est d&rsquo;ouvrir les sciences aux enfants de mani\u00e8re ludique; ainsi, les enfants et les adolescents sont invit\u00e9s \u00e0 d\u00e9couvrir les sciences par le jeu et des activit\u00e9s ludiques.<\/p>\n<p>Le Vaisseau est un lieu d&rsquo;apprentissage, certes, mais qui n&rsquo;en oublie pas pour autant d&rsquo;\u00eatre divertissant.<\/p>\n<p>Les spectateurs sont amen\u00e9s \u00e0 travers 6 espaces th\u00e9matiques \u00e0 en apprendre plus sur le corps humain, les animaux, l&rsquo;eau, la construction, les math\u00e9matiques ou encore la vie du jardin.<\/p>\n<p>Des ateliers, des expositions ou encore des spectacles sont propos\u00e9s au cours de l&rsquo;ann\u00e9e, toujours dans la m\u00eame optique: apprendre en s&rsquo;amusant.<\/p>\n<p>Ainsi, \u00e0 travers toutes ces activit\u00e9s, les \u00e9quipes du Vaisseau rivalisent d\u2019ing\u00e9niosit\u00e9 pour faire d\u00e9couvrir les sciences et plus g\u00e9n\u00e9ralement le monde qui nous entoure.<\/p>\n<p><strong>Notre conseil<\/strong> : un endroit \u00e0 partager en famille<\/p>\n<p>Pour toute information sur le Vaisseau : <a href=\"http:\/\/www.levaisseau.com\/\" target=\"_blank\" rel=\"nofollow noopener\">http:\/\/www.levaisseau.com\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>5) Profiter de la gastronomie<\/h2>\n<p><img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_gastronomie.jpg\" alt=\"Gastronomie\" \/><\/p>\n<p>Strasbourg est indissociable de sa gastronomie, la ville s\u2019en sert comme d\u2019un v\u00e9ritable fer de lance de sa culture \u00e0 travers la France.<\/p>\n<p>Nous pouvons, bien entendu, vous parler de la choucroute, le plat embl\u00e9matique de la ville de Strasbourg fait \u00e0 partir de chou r\u00e2p\u00e9 et mis en saumure dans des tonneaux.<\/p>\n<p>Ici, la choucroute est un monument, elle se d\u00e9guste en toutes saisons et on l&rsquo;accompagne souvent de charcuterie.<\/p>\n<p>Strasbourg se veut une ville gastronomique, qui d\u00e9fend son patrimoine culinaire depuis des si\u00e8cles.<\/p>\n<p>La cuisine alsacienne utilise des produits pour la plupart r\u00e9gionaux; en plus des plats traditionnels, nous pouvons aussi vous conseiller ses charcuteries, comme le jambon et la saucisse de Strasbourg.<\/p>\n<p>On peut noter \u00e9galement les p\u00e2tisseries avec les fameux bretzels mais l&rsquo;Alsace compte aussi un grand nombre de tartes, le kougelhopf \u00e9tant le g\u00e2teau traditionnel par exemple.<\/p>\n<p><strong>Notre conseil<\/strong> : Les mois de d\u00e9cembre et janvier sont des mois festifs donc gourmands.<\/p>\n<p>&nbsp;<\/p>\n<h2>6) Visiter le mus\u00e9e zoologique de Strasbourg<\/h2>\n<p><em>29 Boulevard de la Victoire<br \/>\n<\/em><br \/>\n<img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_musee_zoologique.jpg\" alt=\"Mus\u00e9e zoologique\" \/><\/p>\n<p>Situ\u00e9 au c\u0153ur du campus universitaire de Strasbourg, ce mus\u00e9e a \u00e9t\u00e9 inaugur\u00e9 au 18e si\u00e8cle. Vestige du cabinet d\u2019histoire naturelle de Jean Hermann, il pr\u00e9sente des animaux naturalis\u00e9s, c&rsquo;est-\u00e0-dire empaill\u00e9s.<\/p>\n<p>Avec des animaux naturalis\u00e9s venus de toute la plan\u00e8te, de la Cordill\u00e8re des Andes \u00e0 l&rsquo;Antarctique en passant par la faune r\u00e9gionale d&rsquo;Alsace, la collection du mus\u00e9e est impressionnante, en plus d&rsquo;\u00eatre une des plus grandes de France.<\/p>\n<p>Des animaux rares d&rsquo;Am\u00e9rique Latine c\u00f4toient des animaux plus \u00ab\u00a0communs\u00a0\u00bb comme des lions, des z\u00e8bres ou des animaux marins, mais \u00e9galement des animaux aujourd&rsquo;hui disparus.<\/p>\n<p>Au fil de votre visite, vous voyagerez \u00e0 travers le globe au gr\u00e9 des diff\u00e9rentes salles et animaux que vous pourrez admirer.<\/p>\n<p>Chaque salle est class\u00e9e selon un th\u00e8me et vous permet de profiter d&rsquo;oiseaux, d&rsquo;insectes, de tortues ou encore de kangourous: un vrai panorama de la diversit\u00e9 de la faune sur Terre !<\/p>\n<p>Le mus\u00e9e accueille \u00e9galement r\u00e9guli\u00e8rement des expositions temporaires et des ateliers ludiques destin\u00e9s avant tout aux jeunes, ce qui fait du mus\u00e9e zoologique de Strasbourg un endroit id\u00e9al pour sortir en famille.<\/p>\n<p><strong>Notre conseil \u00a0<\/strong>: Visite \u00e0 privil\u00e9gier en famille<\/p>\n<p>Pour toute information sur le Mus\u00e9e Zoologique : <a href=\"https:\/\/www.musees.strasbourg.eu\/\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/www.musees.strasbourg.eu\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>7) Visiter le Parlement Europ\u00e9en<\/h2>\n<p><em>All\u00e9e du Printemps<br \/>\n<\/em><br \/>\n<img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_parlement_europeen2.jpg\" alt=\"Parlement Europ\u00e9en\" \/><\/p>\n<p>En plus de ses magnifiques monuments et de sa gastronomie, Strasbourg est notamment c\u00e9l\u00e8bre pour abriter le si\u00e8ge officiel du Parlement Europ\u00e9en. Chaque mois, les d\u00e9put\u00e9s s&rsquo;y r\u00e9unissent pendant quatre jours pour voter et d\u00e9battre.<\/p>\n<p>Depuis quelques ann\u00e9es, le Parlement est ouvert au public: durant les semaines de session vous pourrez profiter de ce prestigieux b\u00e2timent.<\/p>\n<p>Au programme: des visites guid\u00e9es, au cours desquelles des myst\u00e8res sur le lieu vous seront r\u00e9v\u00e9l\u00e9s, ainsi qu&rsquo;une r\u00e9trospective sur l&rsquo;histoire de l&rsquo;Europe.<\/p>\n<p>Vous aurez \u00e9galement la possibilit\u00e9 de visiter l&rsquo;h\u00e9micycle o\u00f9 la plupart des s\u00e9ances pl\u00e9ni\u00e8res prennent place.<\/p>\n<p>Depuis peu, le Parlement a \u00e9galement lanc\u00e9 un projet permettant aux jeunes de participer au programme du Parlement Europ\u00e9en : l&rsquo;Euroscola.<\/p>\n<p><strong>Notre conseil<\/strong> : r\u00e9servez \u00e0 l\u2019avance sur le site si vous \u00eates en groupe.<\/p>\n<p>Pour toute information sur le parlement europ\u00e9en : <a href=\"https:\/\/visiting.europarl.europa.eu\/fr\/visitor-offer\/strasbourg\/hemicycle-outside-plenary-sessions\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/visiting.europarl.europa.eu\/fr\/visitor-offer\/strasbourg\/hemicycle-outside-plenary-sessions<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>8) Sortir pour prendre un verre<\/h2>\n<p><img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_place_gayot.jpg\" alt=\"Place du march\u00e9 Gayot\" \/><\/p>\n<p>Strasbourg est une ville parfaite pour quiconque souhaite boire un verre et profiter des terrasses des quartiers commer\u00e7ants.<\/p>\n<p>Si vous souhaitez profiter d&rsquo;un verre, il faut vous diriger vers la \u00ab\u00a0PMG\u00a0\u00bb, comprenez la place du march\u00e9 Gayot. Cette place est assez c\u00e9l\u00e8bre dans Strasbourg, enti\u00e8rement pav\u00e9e et entour\u00e9e par des maisons au style typiquement alsacien, le tout a l&rsquo;ombre de plusieurs arbres.<\/p>\n<p>V\u00e9ritable \u00e9picentre de la ville, la PMG regorge de bars et autre caf\u00e9s.<\/p>\n<p>L\u2019ambiance y est festive, survolt\u00e9e et assez jeune, mais l&rsquo;on peut parfaitement y aller pour se pr\u00e9lasser sur les bancs de la place.<\/p>\n<p>Pour vous faciliter la tache, voici 3 bars: le QG, le Saxo, et le Gayot, ils sont assez similaires mais tous agr\u00e9ables.<\/p>\n<p>Ils proposent une grande terrasse qui sera encore plus appr\u00e9ciable l&rsquo;\u00e9t\u00e9, de la bonne musique mais surtout un calme inh\u00e9rent \u00e0 la place dans sa globalit\u00e9, a l&rsquo;\u00e9cart du tumulte de Strasbourg et des bruits de circulation.<\/p>\n<p>Strasbourg est \u00e9galement une ville fluviale, les quais sont donc une mine d&rsquo;or pour sortir le soir et plus particuli\u00e8rement les p\u00e9niches.<\/p>\n<p>En effet depuis quelques ann\u00e9es les \u00ab\u00a0bar-p\u00e9niche\u00a0\u00bb se sont fortement d\u00e9velopp\u00e9s dans la ville: vous pourrez aller aux quais des bateliers o\u00f9 vous trouverez plusieurs bateaux amarr\u00e9s \u00e0 l&rsquo;ann\u00e9e.<\/p>\n<p>Quelque soit le terrain, marin ou terrestre, Strasbourg est une ville o\u00f9 il fait bon sortir le soir et qui propose plusieurs endroits pour le faire.<\/p>\n<p><strong>Notre conseil<\/strong> : La PMG est tr\u00e8s fr\u00e9quent\u00e9e le soir, il faut venir t\u00f4t pour avoir une place dans un bar.<\/p>\n<p>&nbsp;<\/p>\n<h2>9) Visiter le palais Rohan<\/h2>\n<p><em>2 Place du Ch\u00e2teau<br \/>\n<\/em><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-21357\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/palais-rohan.jpg\" alt=\"palais rohan\" width=\"640\" height=\"426\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/palais-rohan.jpg 640w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/palais-rohan-475x316.jpg 475w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>A votre arriv\u00e9e vous passerez par la cour d&rsquo;honneur et vous pourrez admirer le portail monumental en arc de triomphe surmont\u00e9 de statues repr\u00e9sentant la Cl\u00e9mence et la Religion.<\/p>\n<p>Le palais est divis\u00e9 en trois parties: en effet, il contient 3 mus\u00e9es.<\/p>\n<p>Le premier est le mus\u00e9e d&rsquo;arch\u00e9ologie, il est install\u00e9 ici depuis le 19e si\u00e8cle. Le mus\u00e9e s&rsquo;est sp\u00e9cialis\u00e9 dans les \u00ab\u00a0antiquit\u00e9s nationales\u00a0\u00bb: ainsi, il retrace les premi\u00e8res traces de l&rsquo;occupation humaine, vers 600 000 ans av. J.-C., jusqu&rsquo;\u00e0 l&rsquo;aube du Moyen-\u00e2ge, dans la r\u00e9gion alsacienne.<\/p>\n<p>Des mill\u00e9naires d&rsquo;histoire se succ\u00e8dent ainsi sur plus de 1 200 m2 d\u2019exposition permanente.<\/p>\n<p>Le 2e mus\u00e9e est celui des Beaux-Arts : il pr\u00e9sente une grande collection de peintures du 14e si\u00e8cle au 19e si\u00e8cle, r\u00e9alis\u00e9es par des artistes comme Botticelli, El Greco ou encore Van Dyck.<\/p>\n<p>Il fait \u00e9cho au mus\u00e9e des Arts d\u00e9coratifs qui est constitu\u00e9 de collections de c\u00e9ramiques, de pi\u00e8ces d&rsquo;orf\u00e8vrerie et de mobilier, ainsi que d\u2019une salle d&rsquo;horlogerie pr\u00e9sentant des vestiges de la premi\u00e8re horloge astronomique de la cath\u00e9drale de Strasbourg.<\/p>\n<p><strong>Notre conseil :<\/strong> Pr\u00e9voir une journ\u00e9e compl\u00e8te pour appr\u00e9cier les diff\u00e9rents mus\u00e9es du palais.<\/p>\n<p>&nbsp;<\/p>\n<h2>10) \u00a0Profiter de la Place Kl\u00e9ber<\/h2>\n<p><em>Place Kl\u00e9ber<\/em><\/p>\n<p><img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_place_kleber.jpg\" alt=\"Place Kleber\" \/><\/p>\n<p>La place Kl\u00e9ber est \u00e0 l&rsquo;image de la place Vend\u00f4me \u00e0 Paris: elle incarne le raffinement strasbourgeois.<\/p>\n<p>Cette place du centre-ville est encadr\u00e9e par de nombreuses boutiques avec notamment l&rsquo;Aubette, ce b\u00e2timent que l&rsquo;on surnommait \u00ab\u00a0la chapelle Sixtine de l&rsquo;art moderne\u00a0\u00bb. On peut y retrouver plusieurs boutiques et restaurants, sur une surface de pr\u00e8s de 6000 m\u00b2.<\/p>\n<p>En son centre, on retrouve bien \u00e9videmment la statue Kl\u00e9ber, l&rsquo;\u0153uvre de Philippe Grass construite en 1840.<\/p>\n<p>Elle repr\u00e9sente le g\u00e9n\u00e9ral Jean-Baptiste Kl\u00e9ber tenant la lettre de l&rsquo;amiral Keith qui demandait la capitulation des troupes fran\u00e7aises durant les guerres de la R\u00e9volution fran\u00e7aise.<\/p>\n<p>Un belle place anim\u00e9e qui se r\u00e9v\u00e8le \u00eatre le c\u0153ur de la ville de Strasbourg<\/p>\n<p><strong>Notre conseil :<\/strong> A visiter pendant les f\u00eates de No\u00ebl.<\/p>\n<p>&nbsp;<\/p>\n<h2>11) Le march\u00e9 de Noel<\/h2>\n<p><img decoding=\"async\" src=\"\/images\/infosvilles\/strasbourg_capitale_de_noel.jpg\" alt=\"March\u00e9 de Noel\" \/><\/p>\n<p>Chaque ann\u00e9e du 25 novembre au 31 d\u00e9cembre, Strasbourg accueille le plus grand march\u00e9 de No\u00ebl d&rsquo;Europe.<\/p>\n<p>V\u00e9ritable institution dans la ville, le march\u00e9 permet de d\u00e9couvrir sur plus de 12 sites aux quatre coins de la ville des produits alimentaires r\u00e9gionaux et des d\u00e9corations typiques d\u2019un No\u00ebl alsacien.<\/p>\n<p>Pour cette occasion, la ville est illumin\u00e9e par plusieurs dizaines de kilom\u00e8tres de guirlande: elle arbore ainsi un tout autre visage la nuit que le jour.<\/p>\n<p>La ville de Strasbourg, dans une volont\u00e9 de se renouveler chaque ann\u00e9e, invite un pays \u00e9tranger \u00e0 partager sa culture.<\/p>\n<p>C\u2019est ainsi que des pays comme le Luxembourg, par exemple, ont pu faire d\u00e9couvrir leurs cultures culinaires sur le march\u00e9.<\/p>\n<p><strong>Notre conseil :<\/strong> A visiter de nuit pour profiter des d\u00e9corations illumin\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<h4>Autres articles \u00e0 propos de Strasbourg :<\/h4>\n<ul>\n<li><a href=\"\/fr\/blog\/meilleurs-hotels-strasbourg\/\">Top 10 des meilleurs h\u00f4tels \u00e0 Strasbourg que nous recommandons<\/a><\/li>\n<li><a href=\"\/fr\/blog\/strasbourg-guide-quartiers\/\">Guide des quartiers de Strasbourg : o\u00f9 s\u00e9journer \u00e0 Strasbourg ?<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Bord\u00e9e par le Rhin, la ville de Strasbourg est une ville calme qui a su garder son charme d&rsquo;antan. Lors de votre visite, vous serez &#8230; <a title=\"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg\" class=\"read-more\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/\" aria-label=\"En savoir plus sur Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":21356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-21354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-province","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg absolument<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg absolument\" \/>\n<meta property=\"og:description\" content=\"Bord\u00e9e par le Rhin, la ville de Strasbourg est une ville calme qui a su garder son charme d&rsquo;antan. Lors de votre visite, vous serez ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de France Hotel Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranceHotelGuide\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-08T12:37:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T12:38:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mona\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/\"},\"author\":{\"name\":\"Mona\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\"},\"headline\":\"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg\",\"datePublished\":\"2015-03-08T12:37:19+00:00\",\"dateModified\":\"2021-07-23T12:38:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/\"},\"wordCount\":2350,\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/strasbourg-1.jpg\",\"articleSection\":[\"Province\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/\",\"name\":\"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg absolument\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/strasbourg-1.jpg\",\"datePublished\":\"2015-03-08T12:37:19+00:00\",\"dateModified\":\"2021-07-23T12:38:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/strasbourg-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/strasbourg-1.jpg\",\"width\":640,\"height\":426,\"caption\":\"Strasbourg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/que-faire-a-strasbourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"name\":\"Blog de France Hotel Guide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"France Hotel Guide\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"width\":647,\"height\":90,\"caption\":\"France Hotel Guide\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranceHotelGuide\\\/\",\"https:\\\/\\\/x.com\\\/FranceHotelGuid\",\"https:\\\/\\\/www.instagram.com\\\/francehotelguide\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\",\"name\":\"Mona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"caption\":\"Mona\"},\"description\":\"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg absolument","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg absolument","og_description":"Bord\u00e9e par le Rhin, la ville de Strasbourg est une ville calme qui a su garder son charme d&rsquo;antan. Lors de votre visite, vous serez ... Lire plus","og_url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/","og_site_name":"Blog de France Hotel Guide","article_publisher":"https:\/\/www.facebook.com\/FranceHotelGuide\/","article_published_time":"2015-03-08T12:37:19+00:00","article_modified_time":"2021-07-23T12:38:10+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1.jpg","type":"image\/jpeg"}],"author":"Mona","twitter_misc":{"\u00c9crit par":"Mona","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/#article","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/"},"author":{"name":"Mona","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26"},"headline":"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg","datePublished":"2015-03-08T12:37:19+00:00","dateModified":"2021-07-23T12:38:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/"},"wordCount":2350,"publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1.jpg","articleSection":["Province"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/","name":"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg absolument","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/#primaryimage"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1.jpg","datePublished":"2015-03-08T12:37:19+00:00","dateModified":"2021-07-23T12:38:10+00:00","breadcrumb":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/#primaryimage","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1.jpg","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/strasbourg-1.jpg","width":640,"height":426,"caption":"Strasbourg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/que-faire-a-strasbourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 11 des choses \u00e0 faire et voir \u00e0 Strasbourg"}]},{"@type":"WebSite","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","name":"Blog de France Hotel Guide","description":"","publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization","name":"France Hotel Guide","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","width":647,"height":90,"caption":"France Hotel Guide"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranceHotelGuide\/","https:\/\/x.com\/FranceHotelGuid","https:\/\/www.instagram.com\/francehotelguide\/"]},{"@type":"Person","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26","name":"Mona","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","caption":"Mona"},"description":"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !"}]}},"_links":{"self":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/21354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=21354"}],"version-history":[{"count":2,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/21354\/revisions"}],"predecessor-version":[{"id":21363,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/21354\/revisions\/21363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media\/21356"}],"wp:attachment":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=21354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=21354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=21354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}