{"id":10123,"date":"2014-09-30T10:55:40","date_gmt":"2014-09-30T09:55:40","guid":{"rendered":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?p=10123"},"modified":"2020-05-05T14:38:21","modified_gmt":"2020-05-05T13:38:21","slug":"fondation-louis-vuitton","status":"publish","type":"post","link":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/","title":{"rendered":"Guide complet de la Fondation Louis Vuitton (visites, prix&#8230;)"},"content":{"rendered":"<p><em>La Fondation Louis Vuitton est une fondation d\u2019entreprise cr\u00e9\u00e9e en 2006 ayant pour objectif de promouvoir l\u2019art et la culture, en particulier l\u2019art contemporain, et de p\u00e9renniser les actions de m\u00e9c\u00e9nat engag\u00e9es par le groupe LVMH (Mo\u00ebt Hennessy Louis Vuitton) depuis 1990. Le mus\u00e9e de la Fondation Louis Vuitton a \u00e9t\u00e9 inaugur\u00e9 le 27 octobre 2014 et accueille chaque ann\u00e9e plus d\u2019un million de visiteurs. Le mus\u00e9e est donc tr\u00e8s r\u00e9cent, mais il figure d\u00e9j\u00e0 parmi les must de la capitale. Voici donc pour vous un guide complet du mus\u00e9e de la Fondation Louis Vuitton : acc\u00e8s, tarifs, horaires, programmes, vous trouverez toutes les informations dont vous aurez besoin pour organiser votre visite.<\/em><\/p>\n<figure id=\"attachment_10124\" aria-describedby=\"caption-attachment-10124\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10124 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton.jpg\" alt=\"Fondation Luis Vuitton\" width=\"620\" height=\"414\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton-475x317.jpg 475w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton-300x200.jpg 300w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton-192x128.jpg 192w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-10124\" class=\"wp-caption-text\">Cr\u00e9dits:\u00a0<a href=\"https:\/\/www.flickr.com\/photos\/129231073@N06\/23372953941\" target=\"_blank\" rel=\"noopener noreferrer\">Fred Romero<\/a> sous <a href=\"https:\/\/creativecommons.org\/licenses\/by\/2.0\/\" target=\"_blank\" rel=\"noopener noreferrer\">Creative Commons 2.0<\/a><\/figcaption><\/figure>\n<p><strong>\u00a0<\/strong><\/p>\n<h2>O\u00f9 est la Fondation Louis Vuitton ?<\/h2>\n<p>La Fondation Louis Vuitton se trouve dans la partie nord du Bois de Boulogne, plus exactement dans le Jardin d\u2019Acclimatation. Impossible de la rater : vous la reconna\u00eetrez de loin \u00e0 sa forme si particuli\u00e8re, faisant penser \u00e0 un voilier aux voiles gonfl\u00e9es par le vent d\u2018ouest. Cette architecture quelque peu \u201ctordue\u201d est la signature de l\u2019am\u00e9ricain Frank Ghery, architecte visionnaire qui cr\u00e9e des formes jamais imagin\u00e9es auparavant, et qui r\u00e9volutionne l\u2019utilisation du verre pour donner naissance \u00e0 un \u00e9difice l\u00e9ger, lumineux, unique et novateur. Frank Ghery est d\u2019ailleurs \u00e9galement l\u2019architecte, entre autres, de la cin\u00e9math\u00e8que fran\u00e7aise, elle aussi situ\u00e9e \u00e0 Paris.<\/p>\n<p>&nbsp;<\/p>\n<h2>Comment s\u2019y rendre ?<\/h2>\n<p>Vous pouvez vous rendre \u00e0 la Fondation Louis Vuitton par le m\u00e9tro en descendant \u00e0 la station Les Sablons (ligne 1), sortie Fondation Louis Vuitton. Cette station est aussi desservie par la ligne 73 du bus et se situe \u00e0 une quinzaine de minutes \u00e0 pieds de l\u2019entr\u00e9e de la fondation. Il est \u00e9galement possible de descendre \u00e0 la station Louis Vuitton du bus 244, juste en face de l\u2019entr\u00e9e du mus\u00e9e. Cette station n\u2019est desservie que les week-ends et jours f\u00e9ri\u00e9s. En semaine, ce m\u00eame bus dessert la station Jardin d\u2019acclimatation, \u00e0 10 minutes \u00e0 pieds de la Fondation.<\/p>\n<p>La Fondation met une navette \u00e0 disposition de ses visiteurs. Des rotations sont organis\u00e9es sur les horaires de la Fondation, toutes les 20 minutes environ. Le premier d\u00e9part se fait de la place Charles de Gaulle, \u00e0 l&rsquo;angle de l&rsquo;avenue de Friedland et \u00e0 proximit\u00e9 de la sortie de m\u00e9tro 15 minutes avant l&rsquo;horaire d&rsquo;ouverture de la Fondation. La derni\u00e8re navette part de la Fondation 7 minutes apr\u00e8s la fermeture (pas de navette le mardi, jour de fermeture hebdomadaire de la Fondation). Un billet aller-retour en navette co\u00fbte 2\u20ac, il est gratuit pour les adh\u00e9rents accompagn\u00e9s d\u2019un invit\u00e9 ainsi que pour les personnes en situation de handicap et leur accompagnateur.<\/p>\n<p>Ce service de transport est strictement r\u00e9serv\u00e9 aux visiteurs de la Fondation Louis Vuitton munis d\u2019un billet d\u2019acc\u00e8s et d\u2019un titre de transport valides. Toute personne non munie d\u2019un titre de transport et d\u2019un billet d\u2019acc\u00e8s \u00e0 la Fondation se verra refuser l\u2019acc\u00e8s \u00e0 la navette.<\/p>\n<p>Enfin, si vous souhaitez venir \u00e0 la Fondation Louis Vuitton avec votre v\u00e9hicule personnel, une zone d\u00e9pose-minute ainsi que 5 places de parking pour personnes handicap\u00e9es sont disponibles devant la Fondation. Sinon, il est aussi possible de se garer dans les rues avoisinantes ou \u00e0 Neuilly (Boulevard Maillot par exemple).<\/p>\n<p>Le mus\u00e9e est accessible \u00e0 tout le monde y compris les personnes en situation de handicap. Ces personnes b\u00e9n\u00e9ficient \u00e9galement d\u2019un acc\u00e8s prioritaire \u00e0 l\u2019entr\u00e9e. La priorit\u00e9 d\u2019acc\u00e8s \u00e0 la billetterie et aux entr\u00e9es est \u00e9galement assur\u00e9e aux visiteurs ne pouvant supporter une station debout prolong\u00e9e. Des agents d\u2019accueil et de m\u00e9diation culturelle sont pr\u00e9sents un peu partout dans la fondation pour aider les personnes en situation de handicap.<\/p>\n<p>Pour plus d\u2019informations sur l\u2019accessibilit\u00e9 de la Fondation Louis Vuitton, cliquez <a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/informations-pratiques\/accessibilite-du-batiment.html\" target=\"_blank\" rel=\"noopener noreferrer\">ici<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2>Horaires et tarifs<\/h2>\n<p>Les horaires de la Fondation Louis Vuitton varient en fonction des expositions. En temps normal, la Fondation est ouverte de 11h \u00e0 20h du lundi au jeudi (sauf le mardi, jour de fermeture du mus\u00e9e), de 11h \u00e0 21h le vendredi, et de 11h \u00e0 20h le week-end. Cependant, nous vous conseillons de v\u00e9rifier les horaires avant de vous y rendre, car ils sont souvent modifi\u00e9s.<\/p>\n<p><a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/informations-pratiques.html\" target=\"_blank\" rel=\"noopener noreferrer\">Cliquez ici pour v\u00e9rifier les horaires<\/a>.<\/p>\n<p>Tous les premiers vendredis du mois, la Fondation organise une Nocturne pour voir et vivre autrement son b\u00e2timent, ses \u0153uvres et ses expositions. Lors de ces nocturnes, le mus\u00e9e ferme ses portes \u00e0 23h au lieu de 21h.<\/p>\n<p>Le billet d\u2018entr\u00e9e \u00e0 la Fondation Louis Vuitton co\u00fbte 16\u20ac et donne \u00e9galement acc\u00e8s au Jardin d\u2019acclimatation (qui est situ\u00e9 \u00e0 c\u00f4t\u00e9). Les personnes de moins de 26 ans, les \u00e9tudiants et les enseignants b\u00e9n\u00e9ficient d\u2019une tarif r\u00e9duite \u00e0 10\u20ac. Les personnes de moins de 18 ans, les artistes professionnels, guides interpr\u00e8tes nationaux et r\u00e9gionaux, conf\u00e9renciers nationaux, demandeurs d\u2019emploi et b\u00e9n\u00e9ficiaires des minimas sociaux ont droit au tarif r\u00e9duit (5\u20ac) sur pr\u00e9sentation d\u2019un justificatif. Il existe \u00e9galement une offre \u201cfamille\u201d de 32\u20ac pour un ou deux adultes et jusqu\u2019\u00e0 4 enfants de moins de 18 ans. Les enfants de moins de 3 ans, les personnes en situation de handicap et un de leurs accompagnateurs, les membres de l\u2019ICOM ou de l\u2019ICOMOS, les journalistes et critiques d\u2019art peuvent entrer gratuitement dans la fondation sur pr\u00e9sentation d\u2019un justificatif.<\/p>\n<p>Pour plus d\u2019informations sur les conditions tarifaires, cliquez <a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/conditions-generales-de-vente\/conditions-tarifaires.html\" target=\"_blank\" rel=\"noopener noreferrer\">ici<\/a>.<\/p>\n<p>Vous pouvez acheter vos billets directement \u00e0 la Fondation (quelques bornes sont mises \u00e0 disposition \u00e0 l\u2019ext\u00e9rieur du b\u00e2timent), ou, plus simplement, <a href=\"https:\/\/billetterie.fondationlouisvuitton.fr\/billet-fondation-visite-css5-fondationlouisvuitton-pg1-rg9900.html\" target=\"_blank\" rel=\"noopener noreferrer\">en les r\u00e9servant \u00e0 l\u2019avance sur Internet<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2>Quand faut-il visiter la Fondation Louis Vuitton ?<\/h2>\n<p>La Fondation Louis Vuitton est ouvert toute l\u2019ann\u00e9e. Elle ne ferme que les 1er janvier, 1er mai et 25 d\u00e9cembre, ainsi que les mardis, jour de fermeture hebdomadaire.<\/p>\n<p>Le billet de la Fondation donnant acc\u00e8s au jardin d\u2019acclimatation, de nombreuses familles y viennent le week-end. Nous vous conseillons donc d\u2019\u00e9viter de venir le samedi et surtout le dimanche, car ce sont les deux plus grosses journ\u00e9es d\u2018affluence \u00e0 la Fondation. Il est pr\u00e9f\u00e9rable de venir en semaine, et plut\u00f4t en fin de journ\u00e9e, \u00e0 partir de 16 ou 17h, si vous voulez visiter dans les meilleures conditions possibles. Cependant, n\u2019arrivez pas trop tard non plus \u00e0 la Fondation, car il faut compter au minimum deux heures pour la visiter, plus si vous \u00eates avec des enfants ou si vous voulez prendre le temps de vous promener dans le jardin d\u2018acclimatation.<\/p>\n<p>De plus, nous vous conseillons d\u2019\u00e9viter autant que possible de vous rendre \u00e0 la Fondation durant les 3 premi\u00e8res et 3 derni\u00e8res semaines des expositions temporaires (vous pouvez v\u00e9rifier l\u2019<a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/agenda.html\" target=\"_blank\" rel=\"noopener noreferrer\">agenda<\/a> sur le site de la Fondation Louis Vuitton). En revanche, les nocturnes du vendredi soir ne sont pas tr\u00e8s fr\u00e9quent\u00e9es, profitez-en !<\/p>\n<p>&nbsp;<\/p>\n<h2>Comment visiter la Fondation Louis Vuitton ?<\/h2>\n<p>La Fondation Louis Vuitton dispose, bien s\u00fbr, d\u2019une collection permanente, mais propose aussi des expositions temporaires, des \u00e9v\u00e9nements ponctuels, une programmation musicale riche et diverses activit\u00e9s. Les \u0153uvres de la Fondation sont dispos\u00e9es dans 11 galeries sur 3 niveaux.<\/p>\n<p><strong>Collection permanente<\/strong><\/p>\n<p>La collection permanente, en constante \u00e9volution s&rsquo;organise autour de lignes sensibles qui dessinent quatre directions : Contemplative, Popiste, Expressionniste, Musique\/Son. A l\u2019heure actuelle, la collection est dot\u00e9e de plus de 250 \u0153uvres (architecture, peinture, sculpture, photographie) r\u00e9alis\u00e9es par une centaine d\u2019artistes.<\/p>\n<figure id=\"attachment_10125\" aria-describedby=\"caption-attachment-10125\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10125 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton-2.jpg\" alt=\"Fondation Louis Vuitton\" width=\"620\" height=\"414\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton-2.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton-2-475x317.jpg 475w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton-2-300x200.jpg 300w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton-2-192x128.jpg 192w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-10125\" class=\"wp-caption-text\">Cr\u00e9dits: <a href=\"https:\/\/www.flickr.com\/photos\/dalbera\/35687319654\" target=\"_blank\" rel=\"noopener noreferrer\">Jean-Pierre Dalb\u00e9ra<\/a>\u00a0 sous <a href=\"https:\/\/creativecommons.org\/licenses\/by\/2.0\/\" target=\"_blank\" rel=\"noopener noreferrer\">Creative Commons 2.0<\/a><\/figcaption><\/figure>\n<p>Vous trouverez plus d\u2019informations sur la <a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/collection.html\" target=\"_blank\" rel=\"noopener noreferrer\">collection permanente<\/a> sur le site de la Fondation Louis Vuitton.<\/p>\n<p><strong>Expositions temporaires<\/strong><\/p>\n<p>Deux expositions temporaires sont organis\u00e9es \u00e0 chaque fois en m\u00eame temps \u00e0 la Fondation et durent en moyenne deux mois. Des expositions sont \u00e9galement organis\u00e9es dans le cadre du programme \u201cHors-les-murs\u201d de la Fondation. Ce programme d\u00e9voile des \u0153uvres encore jamais expos\u00e9es de la collection des Espaces Louis Vuitton \u00e0 Tokyo, Munich, Venise et P\u00e9kin, illustrant ainsi la volont\u00e9 de la Fondation de promouvoir des projets internationaux et de les rendre accessibles \u00e0 un public le plus large possible.<\/p>\n<p>Vous trouverez plus d\u2019informations sur les <a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/expositions.html\" target=\"_blank\" rel=\"noopener noreferrer\">expositions temporaires<\/a> sur le site de la Fondation Louis Vuitton.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00c9v\u00e8nements ponctuels<\/strong><\/p>\n<p>Des \u00e9v\u00e8nements ponctuels sont organis\u00e9s fr\u00e9quemment \u00e0 la Fondation Louis Vuitton : des nocturnes, une fois par mois, mais aussi des rencontres avec des artistes, des sociologues, philosophes, scientifiques, anthropologues, etc, ou encore des concours (photo, \u2026).<\/p>\n<p>Vous trouverez plus d\u2019informations sur les <a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/evenements.html\" target=\"_blank\" rel=\"noopener noreferrer\">\u00e9v\u00e8nements organis\u00e9s<\/a> sur le site de la Fondation Louis Vuitton.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Programmation musicale<\/strong><\/p>\n<p>Dans le m\u00eame registre, la Fondation organise des concerts et r\u00e9citals dans son auditorium, ouvert \u00e0 toutes les formes d\u2019expressions artistiques vivantes. Il est un lieu d\u00e9di\u00e9 \u00e0 la cr\u00e9ation, \u00e0 la rencontre entre les musiciens et les artistes issus de toutes disciplines. Il peut accueillir jusqu\u2019\u00e0 1000 personnes, et son architecture et ses \u00e9quipements offrent aux artistes et au public un cadre unique. Les musiciens et cr\u00e9ateurs invit\u00e9s y composent une saison refl\u00e9tant la diversit\u00e9 et la vitalit\u00e9 du monde de la musique.<\/p>\n<p>Vous trouverez plus d\u2019informations sur la <a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/musique.html\" target=\"_blank\" rel=\"noopener noreferrer\">programmation musicale<\/a> sur le site de la Fondation Louis Vuitton.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Activit\u00e9s<\/strong><\/p>\n<p>La Fondation Louis Vuitton porte une attention particuli\u00e8re \u00e0 l\u2019accueil de son public. Diff\u00e9rentes propositions sont offertes aux visiteurs pour r\u00e9pondre \u00e0 la curiosit\u00e9 de chacun, novice ou familier, et partager l\u2019exp\u00e9rience sensible d\u2019un lieu unique. C\u2019est ainsi que des ateliers sont pr\u00e9vus sp\u00e9cialement pour les familles, o\u00f9 un m\u00e9diateur culturel fait d\u00e9couvrir le b\u00e2timent aux enfants et les aide \u00e0 comprendre les expositions. De m\u00eame, un accueil et des ateliers sp\u00e9cifiques peuvent \u00eatre organis\u00e9s pour les groupes scolaires.<\/p>\n<p>Des \u201cmicro-visites\u201d, gratuites et sans r\u00e9servation, guid\u00e9es par un m\u00e9diateur culturel, peuvent \u00eatre effectu\u00e9es tous les jours de 12h30 \u00e0 18h (jusqu\u2019\u00e0 20h le vendredi) en semaine, et de 11h \u00e0 20h les week-ends et tous les jours pendant les vacances. Ces micro-visites durent 15 minutes et font d\u00e9couvrir quelques unes des oeuvres de la Fondation. Elles partent toutes les 30 minutes des niveaux -1, 1 et 2 aux points de rendez-vous signal\u00e9s.<\/p>\n<p>Les visites en nocturne (\u00e0 ne pas confondre avec la Nocturne de la Fondation qui, elle, n\u2019a lieu qu\u2019une fois par mois, le premier vendredi) sont th\u00e9matiques et permettent de d\u00e9couvrir ou d\u2019approfondir une notion de l\u2019exposition en compagnie d\u2019un m\u00e9diateur culturel. Elles ont lieu chaque vendredi \u00e0 partir de 19h et sont elles aussi gratuites et sans r\u00e9servation. Elles durent 45 minutes.<\/p>\n<p>Tous les premiers vendredis du mois, la Fondation organise une Nocturne pour d\u00e9couvrir autrement son b\u00e2timent, ses \u0153uvres et ses expositions. Visites d\u00e9cal\u00e9es, propositions artistiques, musicales, participatives et instants de convivialit\u00e9 rythment ces soir\u00e9es. La Nocturne n\u2019est accessible que sur r\u00e9servation (10\u20ac plein tarif, 5\u20ac tarif r\u00e9duit).<\/p>\n<figure id=\"attachment_15592\" aria-describedby=\"caption-attachment-15592\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15592 size-full\" src=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/fondation-loui-vuitton-nuit.jpg\" alt=\"Fondation Louis Vuitton de nuit\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/fondation-loui-vuitton-nuit.jpg 620w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/fondation-loui-vuitton-nuit-475x267.jpg 475w, https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/fondation-loui-vuitton-nuit-300x169.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-15592\" class=\"wp-caption-text\">Cr\u00e9dits:\u00a0<a href=\"https:\/\/www.flickr.com\/photos\/la_bretagne_a_paris\/15014997603\" target=\"_blank\" rel=\"noopener noreferrer\">Yann Caradec<\/a> sous <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/2.0\/\" target=\"_blank\" rel=\"noopener noreferrer\">Creative Commons 2.0<\/a><\/figcaption><\/figure>\n<p>Sur inscription par <a href=\"mailto:contact@fondationlouisvuitton.fr\" target=\"_blank\" rel=\"noopener noreferrer\">e-mail<\/a> et pr\u00e9sentation d\u2019un justificatif, une m\u00e9diatrice culturelle sourde pourra vous faire une visite guid\u00e9e de la Fondation en langue des signes fran\u00e7aises.<\/p>\n<p>Vous trouverez plus d\u2019informations sur les <a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/activites-visites-ateliers.html\" target=\"_blank\" rel=\"noopener noreferrer\">activit\u00e9s propos\u00e9es<\/a> sur le site de la Fondation Louis Vuitton.<\/p>\n<p>&nbsp;<\/p>\n<h2>Outils de visite<\/h2>\n<p>Trois applications gratuites peuvent \u00eatre t\u00e9l\u00e9charg\u00e9es pour vous aider \u00e0 comprendre la Fondation Louis Vuitton :<br \/>\n&#8211; l\u2019application de la Fondation Louis Vuitton, qui sert d\u2019audioguide et sur laquelle vous pouvez consulter l\u2019agenda de la Fondation (expositions, \u00e9v\u00e8nements, programmation musicale, \u2026) &#8211;<br \/>\ndisponible sur <a href=\"https:\/\/itunes.apple.com\/fr\/app\/fondation-louis-vuitton\/id922479199?mt=8\" target=\"_blank\" rel=\"noopener noreferrer\">App Store<\/a> et <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.flv&amp;hl=fr\" target=\"_blank\" rel=\"noopener noreferrer\">Google Play<\/a>.<br \/>\n&#8211; L\u2019application \u201cArchi Moi\u201d, con\u00e7ue pour les 8-12 ans et qui aide les enfants \u00e0 comprendre l\u2019architecture du b\u00e2timent &#8211; disponible uniquement sur <a href=\"https:\/\/itunes.apple.com\/fr\/app\/apprentice-architect-fondation\/id917315607?ign-mpt=uo%3D8\" target=\"_blank\" rel=\"noopener noreferrer\">App Store<\/a>.<br \/>\n&#8211; L\u2019application \u201cLucky Vibes\u201d, jeu de musique et d\u2019adresse dont les diff\u00e9rents niveaux vous font d\u00e9couvrir des anecdotes sur la Fondation et dont les \u201ccomp\u00e9titions\u201d peuvent vous faire gagner des billets pour la Fondation &#8211; disponible sur <a href=\"https:\/\/itunes.apple.com\/us\/app\/lucky-vibes\/id1207639190?mt=8\" target=\"_blank\" rel=\"noopener noreferrer\">App Store<\/a> et <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.flv.luckyvibes2&amp;hl=fr\" target=\"_blank\" rel=\"noopener noreferrer\">Google Play<\/a>.<\/p>\n<p>Vous trouverez plus d\u2019informations sur les <a href=\"https:\/\/www.fondationlouisvuitton.fr\/fr\/activites-visites-ateliers\/outils-visite.html\" target=\"_blank\" rel=\"noopener noreferrer\">outils de visite<\/a> sur le site de la Fondation Louis Vuitton.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fondation Louis Vuitton est une fondation d\u2019entreprise cr\u00e9\u00e9e en 2006 ayant pour objectif de promouvoir l\u2019art et la culture, en particulier l\u2019art contemporain, et &#8230; <a title=\"Guide complet de la Fondation Louis Vuitton (visites, prix&#8230;)\" class=\"read-more\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/\" aria-label=\"En savoir plus sur Guide complet de la Fondation Louis Vuitton (visites, prix&#8230;)\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":10124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-10123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paris-culture","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guide complet de la Fondation Louis Vuitton (visites, prix...)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide complet de la Fondation Louis Vuitton (visites, prix...)\" \/>\n<meta property=\"og:description\" content=\"La Fondation Louis Vuitton est une fondation d\u2019entreprise cr\u00e9\u00e9e en 2006 ayant pour objectif de promouvoir l\u2019art et la culture, en particulier l\u2019art contemporain, et ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de France Hotel Guide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranceHotelGuide\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-30T09:55:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-05T13:38:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mona\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/\"},\"author\":{\"name\":\"Mona\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\"},\"headline\":\"Guide complet de la Fondation Louis Vuitton (visites, prix&#8230;)\",\"datePublished\":\"2014-09-30T09:55:40+00:00\",\"dateModified\":\"2020-05-05T13:38:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/\"},\"wordCount\":2104,\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/Louis-vuitton.jpg\",\"articleSection\":[\"Culture\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/\",\"name\":\"Guide complet de la Fondation Louis Vuitton (visites, prix...)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/Louis-vuitton.jpg\",\"datePublished\":\"2014-09-30T09:55:40+00:00\",\"dateModified\":\"2020-05-05T13:38:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/Louis-vuitton.jpg\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/Louis-vuitton.jpg\",\"width\":620,\"height\":414,\"caption\":\"Fondation Luis Vuitton\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/fondation-louis-vuitton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guide complet de la Fondation Louis Vuitton (visites, prix&#8230;)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"name\":\"Blog de France Hotel Guide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"France Hotel Guide\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/logo-francehotelguide-1.png\",\"width\":647,\"height\":90,\"caption\":\"France Hotel Guide\"},\"image\":{\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranceHotelGuide\\\/\",\"https:\\\/\\\/x.com\\\/FranceHotelGuid\",\"https:\\\/\\\/www.instagram.com\\\/francehotelguide\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/e69f59ccc81d048ae562bf14b421ed26\",\"name\":\"Mona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.france-hotel-guide.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Mona_avatar-96x96.png\",\"caption\":\"Mona\"},\"description\":\"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide complet de la Fondation Louis Vuitton (visites, prix...)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/","og_locale":"fr_FR","og_type":"article","og_title":"Guide complet de la Fondation Louis Vuitton (visites, prix...)","og_description":"La Fondation Louis Vuitton est une fondation d\u2019entreprise cr\u00e9\u00e9e en 2006 ayant pour objectif de promouvoir l\u2019art et la culture, en particulier l\u2019art contemporain, et ... Lire plus","og_url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/","og_site_name":"Blog de France Hotel Guide","article_publisher":"https:\/\/www.facebook.com\/FranceHotelGuide\/","article_published_time":"2014-09-30T09:55:40+00:00","article_modified_time":"2020-05-05T13:38:21+00:00","og_image":[{"width":620,"height":414,"url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton.jpg","type":"image\/jpeg"}],"author":"Mona","twitter_misc":{"\u00c9crit par":"Mona","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/#article","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/"},"author":{"name":"Mona","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26"},"headline":"Guide complet de la Fondation Louis Vuitton (visites, prix&#8230;)","datePublished":"2014-09-30T09:55:40+00:00","dateModified":"2020-05-05T13:38:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/"},"wordCount":2104,"publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton.jpg","articleSection":["Culture"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/","name":"Guide complet de la Fondation Louis Vuitton (visites, prix...)","isPartOf":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/#primaryimage"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/#primaryimage"},"thumbnailUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton.jpg","datePublished":"2014-09-30T09:55:40+00:00","dateModified":"2020-05-05T13:38:21+00:00","breadcrumb":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/#primaryimage","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton.jpg","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/Louis-vuitton.jpg","width":620,"height":414,"caption":"Fondation Luis Vuitton"},{"@type":"BreadcrumbList","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/fondation-louis-vuitton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Guide complet de la Fondation Louis Vuitton (visites, prix&#8230;)"}]},{"@type":"WebSite","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#website","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","name":"Blog de France Hotel Guide","description":"","publisher":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#organization","name":"France Hotel Guide","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/logo-francehotelguide-1.png","width":647,"height":90,"caption":"France Hotel Guide"},"image":{"@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranceHotelGuide\/","https:\/\/x.com\/FranceHotelGuid","https:\/\/www.instagram.com\/francehotelguide\/"]},{"@type":"Person","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/#\/schema\/person\/e69f59ccc81d048ae562bf14b421ed26","name":"Mona","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","url":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","contentUrl":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-content\/uploads\/2017\/10\/Mona_avatar-96x96.png","caption":"Mona"},"description":"Conseils, bons plans, meilleures adresses, je vous aide dans vos recherches de voyages, activit\u00e9s, h\u00f4tels et restaurants. Que ce soit pour une balade, un week-end, un apr\u00e8s midi ou tout simplement pour trouver un \u00e9tablissement branch\u00e9 o\u00f9 se restaurer, j'ai ce qu\u2019il vous faut. Suivez le guide !"}]}},"_links":{"self":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/10123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=10123"}],"version-history":[{"count":13,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/10123\/revisions"}],"predecessor-version":[{"id":15591,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/10123\/revisions\/15591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media\/10124"}],"wp:attachment":[{"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=10123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=10123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.france-hotel-guide.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=10123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}